{"id":157,"date":"2015-11-17T10:14:34","date_gmt":"2015-11-17T09:14:34","guid":{"rendered":"http:\/\/hertoghetb.cluster005.ovh.net\/fr\/?page_id=157"},"modified":"2016-02-16T12:50:01","modified_gmt":"2016-02-16T11:50:01","slug":"questions-frequemment-posees-par-les-patients-ou-leur-medecin","status":"publish","type":"page","link":"https:\/\/www.hertoghe.eu\/fr\/questions-frequemment-posees-par-les-patients-ou-leur-medecin\/","title":{"rendered":"Questions fr\u00e9quemment pos\u00e9es par les patients ou leur m\u00e9decin"},"content":{"rendered":"<p>Vous trouverez dans cette rubrique les r\u00e9ponses aux questions les plus fr\u00e9quemment pos\u00e9es par les patients lors de la consultation ainsi que les questions des personnes d\u00e9sireuses de venir \u00e0 la consultation.<\/p>\n<p><div class=\"title_code\">Est-il contre nature de prendre des hormones ? <\/div>\n        <div class=\"content_code\"><br \/>\nVous \u00eates pour le NATUREL ! C\u2019est tr\u00e8s bien ! Pour cette raison, justement, prenez le(s) traitement(s) hormonal(aux) dont vous avez besoin ! Traditionnellement, un \u00ab m\u00e9dicament \u00bb est une substance dont la structure et la nature sont \u00e9trang\u00e8res au corps humain. Dans ce sens, les hormones ne sont donc pas des m\u00e9dicaments types, mais des mol\u00e9cules naturellement produites par le corps humain et pour lesquelles le corps est naturellement adapt\u00e9. Elles n\u2019entra\u00eenent pas pour cette raison les effets ind\u00e9sirables typiques des vrais m\u00e9dicaments, quelles que soient les doses prises, aussi minimes soient-elles, et m\u00eame si le patient ne les per\u00e7oit pas. Si votre m\u00e9decin vous prescrit des hormones identiques en tous points \u00e0 celles qui circulent naturellement dans votre sang et trouve les doses adapt\u00e9es \u00e0 votre \u00e9tat, vous ne devriez pas pr\u00e9senter d\u2019effets secondaires. C\u2019est surtout le surdosage, le sous-dosage ou le d\u00e9s\u00e9quilibre qui posent probl\u00e8me en th\u00e9rapie hormonale. Pour l\u2019\u00e9viter, le patient doit \u00eatre mis au courant des signes et sympt\u00f4mes d\u2019exc\u00e8s ou de d\u00e9ficience hormonale de mani\u00e8re \u00e0 ce qu\u2019il puisse lui-m\u00eame contr\u00f4ler la dose du traitement et avertir son m\u00e9decin d\u00e8s le moindre d\u00e9s\u00e9quilibre.<\/p>\n<p><\/div><div class=\"title_code\">Traitements hormonaux et nutritionnels.<\/div>\n        <div class=\"content_code\"><br \/>\nR\u00e9guli\u00e8rement, des publications scientifiques s\u00e9rieuses utilisent le terme contestable de \u00ab <strong>personnes \u00e2g\u00e9es en bonne sant\u00e9<\/strong> \u00bb pour d\u00e9crire les personnes \u00e2g\u00e9es qu\u2019elles \u00e9tudient et chez qui elles ne d\u00e9c\u00e8lent aucune maladie. Mais des personnes \u00e2g\u00e9es \u00ab en bonne sant\u00e9 \u00bb qui afficheraient toutes les marques ext\u00e9rieures de vieillesse typiques de leur \u00e2ge ne peuvent pas r\u00e9ellement jouir d\u2019une sant\u00e9 optimale, semblable \u00e0 celle des jeunes adultes. <strong>Une sant\u00e9 optimale se traduit par une apparence et des performances physiques comparables \u00e0 celles de sujets jeunes<\/strong>. L\u2019apparente absence de maladie ne constitue donc pas, selon mon exp\u00e9rience, un crit\u00e8re suffisant pour appliquer \u00e0 ces personnes \u00e2g\u00e9es le label appr\u00e9ci\u00e9 de \u00ab personnes en bonne sant\u00e9 \u00bb. \u00ab Les taux plus bas d\u2019hormones chez les personnes \u00e2g\u00e9es ne seraient-ils pas une forme d\u2019adaptation au vieillissement ? \u00bb s\u2019interrogent les partisans de la passivit\u00e9 face au vieillissement. Ils pensent au fond d\u2019eux qu\u2019il n\u2019est pas n\u00e9cessaire ni souhaitable de traiter les diminutions hormonales qui surviennent en vieillissant. Ils soup\u00e7onnent sans preuve que la baisse des taux d\u2019hormones chez les personnes \u00e2g\u00e9es pourrait \u00eatre une adaptation protectrice au vieillissement contre la survenue de maladies, en particulier contre le cancer. Mais ils se trompent, car les donn\u00e9es scientifiques montrent que cette baisse d\u2019hormones ne les prot\u00e8ge pas contre les maladies, ni contre la mort. Au contraire, ces taux bas d\u2019hormones favorisent le d\u00e9veloppement de maladies diverses, y compris souvent le cancer, et augmentent fr\u00e9quemment le risque de mourir pr\u00e9matur\u00e9ment.<br \/>\nLa raison est simple. Une personne \u00e2g\u00e9e a un corps qui est approximativement de m\u00eame taille que celui d\u2019un jeune adulte. Des corps de m\u00eame taille ont besoin de taux d\u2019hormones similaires, pas de taux plus bas. En fait, c\u2019est autour de 20 \u00e0 30 ans que la majorit\u00e9 des personnes jouissent de leur meilleure sant\u00e9. Les taux hormonaux que nous avons \u00e0 ces \u00e2ges sont souvent optimaux car adapt\u00e9s \u00e0 la taille et au volume de notre corps. Nous avons besoin de garder ces taux pour rester en bonne sant\u00e9. Toute diminution d\u2019hormones dans le sang engendre des taux plus bas dans les organes, ce qui conduit \u00e0 un moins bon fonctionnement et \u00e0 une moins bonne sant\u00e9. La prise de suppl\u00e9ments hormonaux par une personne en carence hormonale qui corrige ces d\u00e9ficits, r\u00e9tablit le bon fonctionnement des organes, am\u00e9liorant la sant\u00e9.<br \/>\nPoser comme th\u00e9orie que la nature est bien faite et que la baisse des taux hormonaux avec l\u2019\u00e2ge permet au corps d\u2019\u00e9viter le cancer, les maladies cardiaques, etc. est contredit par les faits et les \u00e9tudes scientifiques suivantes, qui montrent l\u2019oppos\u00e9 :<\/p>\n<ol>\n<li>L\u2019incidence du cancer et des maladies cardiaques est de loin la plus \u00e9lev\u00e9e chez le sujet \u00e2g\u00e9 qui est pauvre en hormones, et non pas chez le jeune adulte. Pour la plupart des hormones, les \u00e9tudes scientifiques montrent que plus bas sont leurs taux, plus le risque de maladies li\u00e9es \u00e0 l\u2019\u00e2ge n\u2019augmente. Ce n\u2019est pas seulement vrai pour les maladies cardiaques et les maladies malignes, ce l\u2019est \u00e9galement pour le diab\u00e8te, l\u2019ob\u00e9sit\u00e9, l\u2019ost\u00e9oporose et souvent pour la mortalit\u00e9.<\/li>\n<li>D\u2019autres \u00e9tudes scientifiques ont montr\u00e9 que la prise de traitements hormonaux diminue souvent chez le patient carenc\u00e9 l\u2019incidence de ces maladies li\u00e9es \u00e0 l\u2019\u00e2ge et parfois aussi de la mortalit\u00e9.<\/li>\n<\/ol>\n<p><\/div><div class=\"title_code\">Quels sont les b\u00e9n\u00e9fices des traitements hormonaux et nutritionnels?<\/div>\n        <div class=\"content_code\"><br \/>\nLa qualit\u00e9 de la vie est un terme qui indique chez un individu son degr\u00e9 de bien-\u00eatre et de capacit\u00e9 \u00e0 accomplir des performances, mais il n\u2019existe pas de consensus formel l\u00e0-dessus, si bien que l\u2019Organisation mondiale de la sant\u00e9 (OMS), qui veut contenter tout le monde, a d\u00e9fini en 1994 la qualit\u00e9 de la vie comme \u00ab la perception qu\u2019a un individu de sa place dans l\u2019existence, dans le contexte de la culture et du syst\u00e8me de valeurs dans lesquels il vit, en relation avec ses objectifs, ses attentes, ses normes et ses inqui\u00e9tudes. Il s\u2019agit d\u2019un large champ conceptuel, englobant de mani\u00e8re complexe la sant\u00e9 physique de la personne, son \u00e9tat psychologique, son niveau d\u2019ind\u00e9pendance, ses relations sociales, ses croyances personnelles et sa relation avec les sp\u00e9cificit\u00e9s de son environnement \u00bb.<br \/>\nBref, beaucoup de bla-bla pour d\u00e9finir un \u00e9tat o\u00f9 une personne a de l\u2019\u00e9nergie, et capable d\u2019agir efficacement et se sent bien dans sa peau, qui constitue le premier but des th\u00e9rapies hormonales et nutritionnelles, en plus de l\u2019am\u00e9lioration de la sant\u00e9, qui va de pair. Une d\u00e9ficience hormonale ou nutritionnelle diminue souvent la qualit\u00e9 de la vie (engendrant des plaintes comme de la fatigue, une humeur plus sombre, etc.) et alt\u00e8re la sant\u00e9, permettant \u00e0 des maladies et m\u00eame au vieillissement de s\u2019installer.<br \/>\nL\u2019hormonoth\u00e9rapie et la th\u00e9rapie nutritionnelle bien conduites et prises \u00e0 temps r\u00e9tablissent la qualit\u00e9 de vie et la sant\u00e9 en comblant le d\u00e9ficit en hormones et en micronutriments, faisant dispara\u00eetre les plaintes li\u00e9es \u00e0 la carence.<\/p>\n<p><\/div><div class=\"title_code\">Comment d\u00e9tecter une carence nutritionnelle ou hormonale ?<\/div>\n        <div class=\"content_code\"><br \/>\nIl existe, dans le monde m\u00e9dical, toute une pol\u00e9mique sur la fa\u00e7on de diagnostiquer une carence hormonale et nutritionnelle. De \u00ab grands \u00bb endocrinologues, qui paraissent tr\u00e8s s\u00fbrs d\u2019eux, ne jurent que par les tests de laboratoire, et en particulier ceux du sang. Selon eux, seuls ces tests seraient concluants, mais ils font fi de tout signe clinique, c\u2019est-\u00e0-dire des signes physiques sur le corps du patient et des plaintes qu\u2019il peut exprimer, ce qui indique aussi une carence ! D\u2019autres m\u00e9decins, qui travaillent davantage sur le terrain, ne jurent que par la \u00ab clinique \u00bb. Seuls ces signes et plaintes, qui refl\u00e8tent l\u2019\u00e9tat micronutritionnel et hormonal \u00e0 l\u2018int\u00e9rieur des cellules, seraient r\u00e9v\u00e9lateurs d\u2019une d\u00e9ficience, les tests de laboratoire \u00e9tant peu ou non r\u00e9v\u00e9lateurs de ce qui se d\u00e9roule dans les cellules. Pour ma part, je prends une position interm\u00e9diaire, relative \u00e0 mon exp\u00e9rience. Elle est peut-\u00eatre plus globale et rejoint un consensus plus large d\u2019autres m\u00e9decins. <strong>La d\u00e9tection d\u2019une carence micronutritionelle ou hormonale<\/strong> se base sur un ensemble de donn\u00e9es : les <strong>tests de laboratoire (bien interpr\u00e9t\u00e9s !), l\u2019histoire m\u00e9dicale et la \u00ab clinique \u00bb (plaintes et signes physiques).<\/strong> Cette derni\u00e8re refl\u00e8te les effets finaux de l\u2019activit\u00e9 d\u2019une hormone sur le corps, \u00e9l\u00e9ments essentiels au diagnostic d\u2019une carence hormonale. Sans la clinique, pas de bon diagnostic. Les tests de laboratoire sont \u00e9galement utiles mais doivent faire l\u2019obje d\u2019une interpr\u00e9tation&#8230; mais ceci est une autre histoire, abord\u00e9e dans la prochaine question.<\/p>\n<p><\/div><div class=\"title_code\">Quelles sont les causes d\u2019une d\u00e9ficience nutritionnelle ?<\/div>\n        <div class=\"content_code\"><br \/>\nLes causes principales de d\u00e9ficience nutritionnelle sont un r\u00e9gime pauvre en nutriments comme le r\u00e9gime occidental type -pauvre en aliments frais-, et une mauvaise absorption digestive des nutriments. Des conditions de stress comme la pratique intensive du sport, le stress chronique, la pollution, produisent une surconsommation de nutriments, et donc des besoins accrus, qui ne sont pas couverts par l\u2019alimentation.<\/p>\n<p><\/div><div class=\"title_code\">Quels facteurs peuvent causer une carence hormonale ?<\/div>\n        <div class=\"content_code\"><br \/>\nPlusieurs facteurs peuvent contribuer \u00e0 causer une d\u00e9ficience hormonale:<\/p>\n<ol>\n<li>Le principal responsable de diminution de production hormonale est l\u2019impitoyable <strong>vieillissement progressif des glandes endocrines<\/strong> qui produisent les hormones. Celles-ci s\u2019\u00e9puisent et s\u2019usent au fil des ann\u00e9es et ne parviennent plus \u00e0 remplacer correctement leurs cellules mortes. Dans les cellules restantes les d\u00e9chets s\u2019accumulent et vont freiner la production hormonale, aggravant la situation.<\/li>\n<li>Une <strong>mauvaise alimentation<\/strong> va aggraver l\u2019\u00e9tat de d\u00e9ficience hormonale:<br \/>\nMal manger prive les glandes de substances n\u00e9cessaires \u00e0 la fois au renouvellement de ses constituants et \u00e0 la fabrication de nouvelles hormones. Le mauvais r\u00e9gime rend les glandes d\u00e9faillantes. C\u2019est le gros probl\u00e8me des r\u00e9gimes pauvres en graisses ou en prot\u00e9ines, par exemple, qui privent le corps de graisses et acides amin\u00e9s essentiels \u00e0 la production d\u2019hormones sexuelles, surr\u00e9naliennes, de croissance, etc.) et qui surchargent le corps de produits inad\u00e9quats qui freinent les glandes (c\u2019est aussi, par exemple le cas du chlore de l\u2019eau du robinet et des graisses br\u00fbl\u00e9es)<\/li>\n<li>Les <strong>infections r\u00e9p\u00e9t\u00e9es<\/strong> par virus, bact\u00e9ries, parasites et moisissures ab\u00eement progressivement les tissus glandulaires. Les sujets avec pass\u00e9 important d\u2019infections subissent un affaiblissement plus prononc\u00e9 des glandes endocrines.<\/li>\n<li>Chez certaines personnes le d\u00e9ficit hormonal est d\u00e9j\u00e0 programm\u00e9 dans des <strong>g\u00e8nes d\u00e9ficitaires<\/strong> qui font que ces personnes connaissent un tarissement hormonal plus rapide et plus pr\u00e9coce.<\/li>\n<\/ol>\n<p>Chez chacun de nous, les glandes s\u2019useront t\u00f4t ou tard et les hormones finiront par se rar\u00e9fier. Cependant, la bonne nouvelle est que nous avons les moyens d\u2019\u00e9viter la plus grosse part de ce d\u00e9p\u00e9rissement en comblant les manques hormonaux par des traitements adapt\u00e9s.<\/p>\n<p><\/div><div class=\"title_code\">En cas de carence, a-t-on un besoin temporaire ou permanent de suppl\u00e9ments nutritionnels ou hormonaux?<\/div>\n        <div class=\"content_code\"><br \/>\nPeut-on prendre un suppl\u00e9ment nutritionnel ou hormonal pour une p\u00e9riode d\u00e9finie ou est-ce permanent ? La plupart des suppl\u00e9ments nutritionnels sont prescrits pour une p\u00e9riode limit\u00e9e et ne n\u00e9cessitent pas d\u2019\u00eatre pris de mani\u00e8re permanente.<br \/>\n\u00c0 tous les \u00e2ges de la vie, il est des p\u00e9riodes difficiles durant lesquelles appara\u00eet un besoin accru en vitamines, en min\u00e9raux ou en hormones.<br \/>\nCe besoin peut entra\u00eener un \u00e9tat temporaire de d\u00e9ficience si aucun suppl\u00e9ment n\u2019est administr\u00e9. Un <strong>stress de longue dur\u00e9e<\/strong>, par exemple, augmente la consommation d\u2019hormones et diminue simultan\u00e9ment leur production interne. D\u2019o\u00f9 un \u00e9tat temporaire de d\u00e9ficience hormonale qui peut faire vieillir pr\u00e9matur\u00e9ment.<br \/>\n<strong>Une carence alimentaire grave<\/strong> &#8211; comme l\u2019anorexie mentale chez une adolescente, par exemple &#8211; fait aussi chuter les taux hormonaux et ouvre la voie \u00e0 une d\u00e9gradation (sorte de vieillissement pr\u00e9matur\u00e9) du corps.<br \/>\nIl en va de m\u00eame de la <strong>suralimentation<\/strong> : la consommation excessive de sucreries, d\u2019alcools, qui produisent un stress exag\u00e9r\u00e9 sur le corps, l\u2019affaiblissent et facilitent le d\u00e9clenchement de processus li\u00e9s au vieillissement pr\u00e9matur\u00e9. Citons aussi le <strong>tabagisme, la toxicomanie, les maladies infectieuses, la pollution, le sport intensif<\/strong>, etc., toutes ces agressions qui fragilisent le corps et peuvent l\u2019user pr\u00e9matur\u00e9ment.<br \/>\nLa persistance de ces \u00e9tats d\u00e9favorables rend n\u00e9cessaire l\u2019administration quotidienne de suppl\u00e9ments hormonaux et nutriments manquants. La disparition des \u00e9tats d\u00e9favorables par l\u2019am\u00e9lioration du style de vie et de l\u2019alimentation peut rendre la prise de suppl\u00e9ments nutritionnels inutile (mais rarement celle de suppl\u00e9ments hormonaux).<br \/>\nLa correction des \u00e9tats d\u00e9favorables peut am\u00e9liorer les taux hormonaux, mais est rarement assez efficace pour permettre d\u2019\u00e9viter totalement de prendre des suppl\u00e9ments hormonaux. En conclusion, la suppl\u00e9mentation nutritionnelle est dans beaucoup de cas n\u00e9cessaire seulement temporairement pour une p\u00e9riode de deux \u00e0 six mois par exemple, alors qu\u2019une suppl\u00e9mentation hormonale quotidienne \u00e0 vie, est dans la plupart des cas recommand\u00e9e, car les d\u00e9ficiences hormonales tendent \u00e0 persister, au moins \u00e0 bas bruit, malgr\u00e9 la disparition des conditions d\u00e9favorables.<\/p>\n<p><\/div><div class=\"title_code\">A quel \u00e2ge devrait-on commencer \u00e0 prendre des traitements hormonaux et nutritionnels ?<\/div>\n        <div class=\"content_code\"><br \/>\nUn traitement hormonal et\/ou nutritionnel peut commencer t\u00f4t,<strong> parfois d\u00e8s la naissance<\/strong>, parce qu\u2019il peut d\u00e9j\u00e0 y avoir carence \u00e0 cet \u00e2ge. Un b\u00e9b\u00e9 peut na\u00eetre avec une carence hormonale et\/ou vitaminique parce que durant la grossesse la m\u00e8re ne s\u2019est pas bien aliment\u00e9e ou encore parce que le b\u00e9b\u00e9 a de moins bons g\u00e8nes. Beaucoup de jeunes, enfants et jeunes adultes, ont de bons taux hormonaux et n\u2019ont pas besoin de suppl\u00e9mentation hormonale, du moins si leur alimentation est suffisamment bonne, ce qui semble \u00eatre de moins en moins le cas dans notre soci\u00e9t\u00e9 moderne. Cependant, <strong>pour la plupart des gens, les traitements hormonaux deviennent n\u00e9cessaires d\u00e8s l\u2018\u00e2ge de 30 \u00e0 45 ans<\/strong>, afin de corriger les carences hormonales qui apparaissent \u00e0 ces \u00e2ges. Une diminution progressive de taux hormonaux qui engendre une forme tr\u00e8s mod\u00e9r\u00e9e de vieillissement commence \u00e0 partir de l\u2019\u00e2ge de 25 \u00e0 35 ans, et devient visible vers 40-50 ans. La vitesse de d\u00e9clin hormonal est variable selon les personnes, mais t\u00f4t ou tard personne n\u2019y \u00e9chappe, ce qui veut aussi dire que t\u00f4t ou tard tout le monde aura besoin de suppl\u00e9ments hormonaux.<br \/>\nNote : \u00c0 l\u2019avenir, il est probable que les <strong>b\u00e9b\u00e9s<\/strong> soient soumis dans les maternit\u00e9s \u00e0 des investigations de pointe syst\u00e9matiques en vue de d\u00e9tecter des micro-carences hormonales et qu\u2019ils se feront traiter par des <strong>micro-doses appropri\u00e9es<\/strong> pour garantir les chances de b\u00e9n\u00e9ficier d\u2019une sant\u00e9 optimale. Mais nous n\u2019en sommes pas encore l\u00e0. Quant aux traitements di\u00e9t\u00e9tiques, en vitamines et en oligo-\u00e9l\u00e9ments, nous pensons que <strong>d\u00e8s le plus jeune \u00e2ge<\/strong>, celui du b\u00e9b\u00e9 ou du petit enfant, tout doit \u00eatre fait pour optimiser les taux.<\/p>\n<p><\/div><div class=\"title_code\">A quel \u00e2ge commence-t-on un traitement hormonal et nutritionnel et\/ou de long\u00e9vit\u00e9 ?<\/div>\n        <div class=\"content_code\"><br \/>\nUn traitement hormonal et\/ou nutritionnel peut commencer t\u00f4t, <strong>parfois d\u00e8s la naissance<\/strong>, parce qu\u2019il peut d\u00e9j\u00e0 y avoir carence \u00e0 cet \u00e2ge. Un b\u00e9b\u00e9 peut na\u00eetre avec une carence hormonale et\/ou vitaminique parce que durant la grossesse la m\u00e8re ne s\u2019est pas bien aliment\u00e9e ou encore parce que le b\u00e9b\u00e9 a des moins bons g\u00e8nes.<br \/>\nBeaucoup de jeunes, enfants et jeunes adultes, ont de bons taux hormonaux et ne n\u00e9cessitent pas de suppl\u00e9mentation hormonale, du moins si leur alimentation est suffisamment bonne,-ce qui semble \u00eatre de moins en moins le cas dans notre soci\u00e9t\u00e9 moderne. Cependant, <strong>pour la plupart des gens, les traitements hormonaux deviennent n\u00e9cessaires d\u00e8s l\u2018\u00e2ge de 30 \u00e0 45 ans<\/strong>, afin de corriger les carences hormonales qui apparaissent \u00e0 ces \u00e2ges.<br \/>\nUne diminution progressive de taux hormonaux qui engendre une forme tr\u00e8s mod\u00e9r\u00e9e de vieillissement commence \u00e0 partir de l\u2019\u00e2ge de 25 \u00e0 35 ans, et devient visible vers 40-45-50 ans. La vitesse de d\u00e9clin hormonal est variable selon les personnes, mais t\u00f4t ou tard personne n\u2019y \u00e9chappe, ce qui veut dire aussi que t\u00f4t ou tard tout le monde aura besoin de suppl\u00e9ments hormonaux.<br \/>\nNote : \u00c0 l\u2019avenir, il est probable que les <strong>b\u00e9b\u00e9s<\/strong> seront syst\u00e9matiquement soumis dans les maternit\u00e9s \u00e0 des investigations pointues en vue de d\u00e9tecter des <strong>micro-carences hormonales<\/strong>, et qu\u2019ils se feront traiter par des micro-doses appropri\u00e9es afin de leur garantir les chances de b\u00e9n\u00e9ficier d\u2019une sant\u00e9 optimale. Mais nous n\u2019en sommes pas encore l\u00e0.<br \/>\nQuant aux traitements di\u00e9t\u00e9tiques, vitaminiques et en oligo-\u00e9l\u00e9ments, nous pensons que d\u00e8s le plus jeune \u00e2ge, chez le b\u00e9b\u00e9 ou petit enfant, tout devrait \u00eatre fait pour optimiser les taux.<\/p>\n<p><\/div><div class=\"title_code\">A quel \u00e2ge les taux hormonaux sont-ils optimaux ?<\/div>\n        <div class=\"content_code\"><br \/>\n<strong>Chaque personne est unique avec un \u00e9tat hormonal et nutritionnel optimal<\/strong> qui lui est propre. Pour la <strong>majorit\u00e9 des femmes<\/strong>, la p\u00e9riode optimale de sant\u00e9 hormonale se situe entre <strong>18 et 23 ans<\/strong> ; chez l\u2019<strong>homme<\/strong> souvent entre <strong>21 et 25 ans<\/strong>. C\u2019est \u00e0 ces \u00e2ges que la plupart des taux hormonaux sont les plus \u00e9lev\u00e9s. Cet \u00e9tat optimal une fois atteint, beaucoup de jeunes restent dans cette condition optimale jusqu\u2019\u00e0 l\u2019\u00e2ge de 30 ans. Apr\u00e8s commence le d\u00e9clin, d\u2019abord tr\u00e8s lentement et de mani\u00e8re pratiquement invisible, puis -vers 40 ans- de plus en plus \u00e9vident.<br \/>\nL\u2019id\u00e9al, serait de faire un <strong>premier bilan de sant\u00e9<\/strong> avec contr\u00f4le rigoureux de l\u2019\u00e9tat hormonal et nutritionnel durant la p\u00e9riode optimale de sant\u00e9 entre 18 et 23 ans chez la femme par exemple, et entre 21 et 25 ans chez l\u2019homme. A cet \u00e2ge, l\u2019individu pr\u00e9sente rarement de grosses carences et les taux hormonaux peuvent, chez beaucoup, \u00eatre consid\u00e9r\u00e9s comme proches de l\u2019optimal. Les taux d\u2019hormones d\u2019un jeune adulte sont souvent les taux optimaux pour une bonne sant\u00e9, et peuvent servir de r\u00e9f\u00e9rence pour plus tard quand des carences hormonales apparaissent et doivent \u00eatre corrig\u00e9es.<\/p>\n<p><\/div><div class=\"title_code\">Quels sont les probl\u00e8mes ou risquent d\u2019une th\u00e9rapie hormonale ?<\/div>\n        <div class=\"content_code\"><br \/>\nDivers types de risques pr\u00e9dominent : le surdosage, le d\u00e9s\u00e9quilibre hormonal et des effets ind\u00e9sirables atypiques :<\/p>\n<ol>\n<li><strong>Le surdosage :<\/strong> Tout comme le manque d\u2019hormones est nuisible, en diminuant la qualit\u00e9 de la vie et la sant\u00e9, l\u2019exc\u00e8s d\u2019hormones produit des effets d\u00e9sagr\u00e9ables. Ces signes physiques et plaintes de surdosage viennent en r\u00e8gle g\u00e9n\u00e9rale tr\u00e8s vite,<strong> en un \u00e0 trois jours<\/strong>, et sont souvent <strong>facilement reconnaissables<\/strong> par le patient lui-m\u00eame ce qui lui permet de rapidement diminuer la dose et r\u00e9tablir la situation.<\/li>\n<li><strong>Le d\u00e9s\u00e9quilibre hormonal<\/strong> est un autre probl\u00e8me. Lors de traitements hormonaux, un taux d\u2019hormones peut devenir excessif par rapport \u00e0 un autre, entrainant souvent des effets atypiques. Un mauvais \u00e9quilibre peut par exemple survenir chez une femme entre les deux hormones f\u00e9minines \u0153stradiol et progest\u00e9rone. Les seins sont douloureusement tendus et le ventre ballonn\u00e9 lorsque le taux de progest\u00e9rone est insuffisant par rapport au taux d\u2019\u0153stradiol. Il suffit d\u2019ajouter ou augmenter la progest\u00e9rone, et \u00e9ventuellement de diminuer l\u2019\u0153stradiol pour restaurer l\u2019\u00e9quilibre.<br \/>\nD\u2019autres \u00e9quilibres hormonaux doivent \u00eatre respect\u00e9s : l\u2019\u00e9quilibre chez la femme entre hormones m\u00e2les et DHEA d\u2019une part et hormones f\u00e9minines d\u2019autre part, l\u2019\u00e9quilibre entre hormones thyro\u00efdiennes et hormones f\u00e9minines, l\u2019\u00e9quilibre entre hormone de croissance ou m\u00e9latonine, hormones calmantes et relaxantes d\u2019une part, et hormones thyro\u00efdiennes ou cortisol, hormones excitantes d\u2019autre part, etc. Pour trouver les dosages corrects et corriger ces d\u00e9s\u00e9quilibres hormonaux, le m\u00e9decin doit acqu\u00e9rir de l\u2019exp\u00e9rience. Le patient doit lui aussi acqu\u00e9rir de l\u2019exp\u00e9rience. Il peut aider son m\u00e9decin \u00e0 trouver l\u2019\u00e9quilibre hormonal optimal en apprenant \u00e0 reconna\u00eetre les signes et plaintes li\u00e9s au manque ou exc\u00e8s des hormones qu\u2019il prend \u2013 cela gr\u00e2ce une information qui lui est g\u00e9n\u00e9ralement donn\u00e9e.<\/li>\n<li><strong>Des effets ind\u00e9sirables graves sont fort rares et g\u00e9n\u00e9ralement pas observ\u00e9s<\/strong> avec les traitements aux hormones bio-identiques, substances naturelles propres au corps, contrairement aux dangers de certains m\u00e9dicaments cr\u00e9\u00e9s par l\u2019industrie pharmaceutique qui donnent facilement des effets ind\u00e9sirables, parfois m\u00eame \u00e0 doses minimes, parce que leur structure mol\u00e9culaire ne convient pas aussi bien au corps humain que les traitements hormonaux \u00e0 mol\u00e9cules bio-identiques. Ils sont pour cette raison aussi potentiellement plus toxiques. Cependant, les traitements hormonaux peuvent \u00e9galement donner des<strong> effets ind\u00e9sirables atypiques qui ne mettent pas la vie en danger<\/strong>. C\u2019est assez souvent d\u00fb \u00e0 des additifs pr\u00e9sents dans les pr\u00e9parations hormonales que le patient ne tol\u00e8re pas.<\/li>\n<\/ol>\n<p><\/div><div class=\"title_code\">Quels sont les effets secondaires des th\u00e9rapies hormonales ?<\/div>\n        <div class=\"content_code\"><br \/>\nComme tout m\u00e9dicament, les traitements hormonaux peuvent donner des effets secondaires de surdosage ou d\u00fbs \u00e0 un d\u00e9s\u00e9quilibre entre une hormone et une autre (une hormone \u00e9tant relativement trop fortement dos\u00e9e par rapport \u00e0 une autre, requ\u00e9rant que l\u2019on augmente aussi le niveau de l\u2019hormone d\u00e9ficiente). C\u2019est pour cette raison qu\u2019au d\u00e9but d\u2019un traitement hormonal on doit revenir plus souvent en consultation pour un contr\u00f4le des doses.<\/p>\n<p><\/div><div class=\"title_code\">Les produits des traitements hormonaux couramment utilis\u00e9s sont-ils de bonne qualit\u00e9 ? <\/div>\n        <div class=\"content_code\"><br \/>\nOui, en g\u00e9n\u00e9ral les hormones sont achet\u00e9es et vendues en pharmacie et sont livrables uniquement sur prescription m\u00e9dicale, ce qui est la garantie d\u2019un produit de qualit\u00e9. La quasi totalit\u00e9 des hormones sont enregistr\u00e9es comme traitement dans la pharmacop\u00e9e officielle du pays. Il n\u2019en va pas de m\u00eame pour les hormones que l\u2019on peut acheter sans prescription m\u00e9dicale par Internet. Pour l\u2019hormone de croissance, par exemple, traitement hormonal disponible sur prescription m\u00e9dicale en pharmacie, il y a un march\u00e9 parall\u00e8le, sur Internet et dans les centres de body building. On retrouve le ph\u00e9nom\u00e8ne aussi dans certains pays \u00e9trangers en voie de d\u00e9veloppement o\u00f9 aucune prescription m\u00e9dicale n\u2019est n\u00e9cessaire, et o\u00f9 fourmillent toutes sortes de marques diff\u00e9rentes, les unes soi-disant meilleures que les autres. Presque syst\u00e9matiquement, lorsqu\u2019on a pu v\u00e9rifier chez un patient les effets d\u2019une hormone de croissance achet\u00e9e dans le circuit parall\u00e8le, les effets de ces traitements pris aux petites doses n\u00e9cessaires pour r\u00e9tablir une carence se sont r\u00e9v\u00e9l\u00e9s d\u00e9cevants ou insuffisants. Pas \u00e9tonnant parce que le contenu et la qualit\u00e9 de ces produits ne sont pas contr\u00f4l\u00e9s par un organisme ind\u00e9pendant. Le manque d\u2019effet n\u2019est pas toujours caus\u00e9 par un mauvais produit en soi, parfois le traitement ne fonctionne pas avec ce produit simplement parce que il n\u2019y pas de conservateur dans le flacon, ce qui rend le produit inefficace trois \u00e0 quatre jours apr\u00e8s qu\u2019un flacon ait \u00e9t\u00e9 entam\u00e9. J\u2019ai moi-m\u00eame \u00e9t\u00e9 contact\u00e9 par une firme qui livrait une de ces hormones de croissance : j\u2019ai d\u00fb injecter huit fois la dose normale pour obtenir les m\u00eames effets b\u00e9n\u00e9fiques qu\u2019avec la pr\u00e9paration achet\u00e9e en pharmacie !<br \/>\nIl y a eu une \u00e9poque pendant laquelle la DHEA \u00e9tait en vente libre aux \u00c9tats-Unis et le contenu des capsules ne correspondait souvent pas \u00e0 ce qui \u00e9tait indiqu\u00e9 sur l\u2019\u00e9tiquette de la bo\u00eete. Elle est toujours en vente libre, mais dans la majorit\u00e9 des cas, le contenu correspond \u00e0 ce qui est d\u00e9sign\u00e9. Mon exp\u00e9rience, cependant, aupr\u00e8s de mes patients qui prennent de la DHEA achet\u00e9e en vente libre, est que leurs taux sanguins de DHEA sulfate dans le sang apr\u00e8s prise de DHEA sont parfois inf\u00e9rieurs \u00e0 ceux attendus. Bref, si vous obtenez votre pr\u00e9paration hormonale en pharmacie, le produit vendu a \u00e9t\u00e9 officiellement enregistr\u00e9 et est garanti de qualit\u00e9. Parfois, quand le produit n\u2019est pas disponible en pharmacie dans un pays donn\u00e9, il faut le faire venir de l\u2019\u00e9tranger. Dans ce cas-l\u00e0, il faut que le fabriquant puisse vous envoyer sa fiche de contr\u00f4le de produit analys\u00e9 par un organisme officiel et ind\u00e9pendant. Toute autre source est \u00e0 rejeter : il faut une garantie de qualit\u00e9 par un certificat ad hoc que la firme doit pouvoir vous montrer.<\/p>\n<p><\/div><div class=\"title_code\">Pouvons-nous vivre plus longtemps en prenant des traitements hormonaux ?<\/div>\n        <div class=\"content_code\"><br \/>\nLes th\u00e9rapies hormonales seules n\u2019offrent \u00e9videmment pas la vie \u00e9ternelle, mais quand elles sont bien men\u00e9es, elles peuvent faire vivre probablement plus longtemps et certainement plus agr\u00e9ablement. Les r\u00e9sultats obtenus lors d&rsquo;exp\u00e9riences sur des animaux et sur des sujets humains sugg\u00e8rent ou confirment cette augmentation de la long\u00e9vit\u00e9 pour une s\u00e9rie de taux \u00e9lev\u00e9s ou traitements hormonaux (tels que ceux \u00e0 la m\u00e9latonine, \u00e0 l&rsquo;hormone de croissance, \u00e0 la DHEA, aux \u0153strog\u00e8nes, \u00e0 la testost\u00e9rone, \u00e0 l\u2019IGF-1, etc.). Cette augmentation de la long\u00e9vit\u00e9 par traitements hormonaux s\u2018explique par l\u2019effet protecteur de nombreuses hormones contre le d\u00e9veloppement de bien des maladies li\u00e9es au vieillissement qui accroissent la mortalit\u00e9. Les maladies cardiaques et vasculaires, les cancers et les infections causent la mort de pr\u00e8s de 90 % des adultes \u00e2g\u00e9s. De combien d\u2019ann\u00e9es les th\u00e9rapies hormonales pourraient-elles probablement prolonger votre vie ? Dix, vingt ou trente ans ? Ou plus ? Il est encore trop t\u00f4t pour le dire. Personnellement, j&rsquo;estime que l\u2019association de suppl\u00e9ments hormonaux bien \u00e9quilibr\u00e9s peut prolonger la vie de dix \u00e0 vingt ans, tout en offrant une p\u00e9riode proportionnellement plus importante encore de qualit\u00e9 de vie et de sant\u00e9 meilleures.<\/p>\n<p><\/div><div class=\"title_code\">Comment les traitements hormonaux, les suppl\u00e9ments nutritionnels ou l\u2019am\u00e9lioration di\u00e9t\u00e9tique qui augmente les taux hormonaux peuvent-ils nous aider \u00e0 mieux nous sentir dans notre peau ? <\/div>\n        <div class=\"content_code\"><br \/>\n<strong>Les traitements hormonaux enl\u00e8vent les sentiments \u00ab parasites \u00bb<\/strong> comme une fatigue continuelle, une anxi\u00e9t\u00e9 r\u00e9currente, des pics de d\u00e9pression r\u00e9guliers qui sont dus au manque hormonal et qui nous rendent mal dans notre peau. \u00c0 titre d\u2019exemple, voici ce que certains traitements peuvent faire et comment ils y arrivent :<\/p>\n<ul>\n<li>Le manque d\u2019hormones thyro\u00efdiennes produit une fatigue le matin au lever et \u00e0 tout arr\u00eat d\u2019activit\u00e9 pendant la journ\u00e9e. L\u2019humeur matinale est plus sombre. Le traitement aux hormones thyro\u00efdiennes inverse la tendance. Il y arrive en stimulant les mitochondries \u2013 sorte de petites centrales d\u2019\u00e9nergie \u00e0 l\u2019int\u00e9rieur des cellules \u2013 \u00e0 produire plus d\u2019ATP et de NADPH, des mol\u00e9cules qui permettent de stocker l\u2019\u00e9nergie et de la lib\u00e9rer quand il le faut. Les hormones thyro\u00efdiennes acc\u00e9l\u00e8rent aussi le flux de sang dans les art\u00e8res et donc l\u2019arriv\u00e9e aux tissus-cible de nutriments.<\/li>\n<li>Le cortisol est une hormone qui augmente aussi l\u2019\u00e9nergie. Elle le fait en acc\u00e9l\u00e9rant le flux sanguin et donc am\u00e9liore l\u2019apport de sang et de nutriments aux cellules. Elle augmente le stock de glycog\u00e8ne dans les muscles et le foie. Le cortisol procure une sensation de plus grande fra\u00eecheur et d\u2019\u00e9nergie ; il permet d\u2019\u00eatre d\u2019attaque (combatif) pour affronter les \u00e9v\u00e9nements stressants.<\/li>\n<li>Les traitements \u00e0 l\u2019hormone de croissance et aux androg\u00e8nes peuvent acc\u00e9l\u00e9rer la r\u00e9cup\u00e9ration apr\u00e8s un effort, et ainsi rendre les personnes qui font des efforts physiques mieux dans leur peau. Les deux hormones stimulent le syst\u00e8me parasympathique, qui calme et r\u00e9duit ainsi consid\u00e9rablement les angoisses inutiles. L\u2019hormone de croissance surtout apaise profond\u00e9ment, donnant du courage et de la paix int\u00e9rieure, effets typiques d\u2019un syst\u00e8me nerveux parasympathique stimul\u00e9. Les androg\u00e8nes rendent le caract\u00e8re plus ferme, plus d\u00e9termin\u00e9, plus courageux aussi.<\/li>\n<li>Les \u0153strog\u00e8nes \u2013les hormones f\u00e9minines \u2013apportent du \u00ab peps \u00bb et du piquant en partie en se transformant en cat\u00e9chol estrog\u00e8nes, sorte d\u2019adr\u00e9naline qui est \u00e0 la base des r\u00e9actions parfois assez vives de certaines femmes. Ces hormones sont tr\u00e8s efficaces pour enlever les d\u00e9pressions caus\u00e9es ou favoris\u00e9es par la carence en hormones f\u00e9minines comme celle qui peut survenir \u00e0 la m\u00e9nopause.<\/li>\n<li>La m\u00e9latonine r\u00e9tablit l\u2019\u00e9nergie en faisant mieux dormir et donc mieux r\u00e9cup\u00e9rer. Elle donne un sommeil plus r\u00e9parateur en rel\u00e2chant tous les muscles et en permettant de s\u2019endormir plus rapidement.<br \/>\nBref, ces b\u00e9n\u00e9fices possibles des traitements hormonaux expliquent pourquoi tant de patients peuvent <strong>se sentir<\/strong> <strong>mieux dans leur peau<\/strong> en suivant une th\u00e9rapie souvent multi-hormonale bien dos\u00e9e.<\/li>\n<\/ul>\n<p><\/div><div class=\"title_code\">Les traitements hormonaux ne sont-ils pas efficaces de mani\u00e8re limit\u00e9e dans le temps, pendant 5 \u00e0 10 ans par exemple, et puis\u2026tout s\u2019\u00e9croule ? <\/div>\n        <div class=\"content_code\"><br \/>\nCertaines personnes, y compris certains m\u00e9decins, s\u2019opposent aux traitements hormonaux parce qu\u2019ils croient, \u00e0 tort, que ces traitements ne sont que de la poudre aux yeux. Selon eux, ces traitements marcheraient bien pendant 5 \u00e0 10 ans mais feraient ensuite r\u00e9gresser le patient dans une situation pire qu\u2019avant \u00e0 cause de leurs effets trop stimulateurs qui br\u00fbleraient ses r\u00e9serves. Cette fausse croyance ne s\u2019appuie sur aucune donn\u00e9e scientifique quand de petites doses physiologiques sont donn\u00e9es. C\u2019est exactement l\u2019inverse ! La sant\u00e9 du patient, au bout de dix \u00e0 vingt ans de traitements hormonaux bien conduits, est g\u00e9n\u00e9ralement meilleure que ce qui \u00e9tait pr\u00e9visible sans correction hormonale. Ceux qui ont b\u00e9n\u00e9fici\u00e9 des bienfaits de th\u00e9rapies hormonales judicieusement adapt\u00e9es ne d\u00e9sirent absolument pas retourner dans l\u2019\u00e9tat de souffrances inutiles de la d\u00e9ficience hormonale qu\u2019ils avaient auparavant ! Un traitement hormonal bien conduit am\u00e9liore la sant\u00e9 \u00e0 long terme et n\u2019a pas d\u2019impact n\u00e9gatif par la suite, m\u00eame si l\u2019on arr\u00eatait apr\u00e8s une vingtaine d\u2019ann\u00e9es. On peut tenir le m\u00eame raisonnement pour l\u2019utilisation des lunettes qui corrigent la vue : quand on enl\u00e8ve ses lunettes, on voit de nouveau moins bien, mais pas plus mal qu\u2019avant\u2026<\/p>\n<p><\/div><div class=\"title_code\">Les traitements hormonaux sont-ils n\u00e9cessaires pour une majorit\u00e9 d\u2019entre nous, y compris toutes les personnes \u00e2g\u00e9es ?<\/div>\n        <div class=\"content_code\"><br \/>\nCertaines personnes croient \u00e0 tort que la majorit\u00e9 des personnes \u00e2g\u00e9es n\u2019ont pas besoin de th\u00e9rapies hormonales. Cependant, la science a d\u00e9montr\u00e9 et red\u00e9montr\u00e9 que les taux d\u2019hormones diminuent avec l\u2019\u00e2ge et que ces diminutions sont li\u00e9es \u00e0 des pertes de capacit\u00e9 physique et mentale, des troubles \u00e9motionnels et un risque accru de maladie. Certaines diminutions hormonales peuvent \u00e9galement faire mourir plus vite. Pour pouvoir jouir d\u2019un bon mental et d\u2019une bonne sant\u00e9 et pour profiter de la vie tout simplement, nous devons corriger nos d\u00e9ficiences hormonales li\u00e9es \u00e0 l\u2019\u00e2ge par des suppl\u00e9ments d\u2019hormones. Il n\u2019y a, \u00e0 ma connaissance, aucune donn\u00e9e s\u00e9rieuse capable de le contester. De plus, le vieillissement de la population entra\u00eene un probl\u00e8me \u00e9conomique inqui\u00e9tant : les personnes \u00e2g\u00e9es ne semblent plus capables de travailler et co\u00fbtent cher \u00e0 la communaut\u00e9 en pensions de retraite et en soins m\u00e9dicaux. N\u2019est-ce pas une solution int\u00e9ressante que d\u2019opter pour une m\u00e9decine pro-aging ou reversing aging ? N\u2019avons-nous pas le devoir d\u2019emp\u00eacher autant que possible que ces personnes \u00e2g\u00e9es tombent malades, perdent leurs capacit\u00e9s mentales et physiques et deviennent incapables de s\u2019assumer seules \u00e9conomiquement et socialement ?<br \/>\nD\u2019autre part, la m\u00e9decine pro-aging et reversing aging trouve d\u00e9j\u00e0 sa justification dans la forte demande (et le besoin) de la population de recevoir des traitements qui pr\u00e9viennent ou att\u00e9nuent les effets du vieillissement. Si les m\u00e9decins n\u2019aident pas les personnes demandeuses de traitements anti-\u00e2ge, celles-ci iront vers une forme d\u2019autotraitement ou vers des m\u00e9decines parall\u00e8les mal contr\u00f4l\u00e9es qui peuvent d\u00e9raper.<\/p>\n<p><\/div><div class=\"title_code\">Comment \u00e9viter ou r\u00e9duire la survenue de cancer par traitements hormonaux ?<\/div>\n        <div class=\"content_code\"><br \/>\nJe sais que j\u2019ai abord\u00e9 cette question de nombreuses fois, mais comme les questions sont r\u00e9currentes \u00e0 ce sujet, permettez-moi de revenir sur les recommandations \u00e0 suivre pour diminuer le risque de cancer. Il y a un pr\u00e9jug\u00e9 largement r\u00e9pandu aupr\u00e8s du grand public, des m\u00e9decins et des chercheurs qui voudrait qu&rsquo;une th\u00e9rapie hormonale \u00ab pourrait causer un cancer, on ne sait jamais \u00bb. Pourtant, l\u2019hormonoth\u00e9rapie correctement adapt\u00e9e n\u2019a pas montr\u00e9, dans la plupart des \u00e9tudes chez les hommes et les femmes, d\u2019effets stimulateurs du d\u00e9veloppement de cancer(s). Face \u00e0 quelques \u00e9tudes sugg\u00e9rant l\u2019implication d\u2019hormonoth\u00e9rapie (f\u00e9minine) mal \u00e9quilibr\u00e9e dans certains cancers de la sph\u00e8re g\u00e9nitale, surtout \u00e0 l&rsquo;aide d&rsquo;hormones non bio-identiques (dont la structure a \u00e9t\u00e9 artificiellement modifi\u00e9e par rapport \u00e0 l\u2019hormone naturellement pr\u00e9sente dans le corps humain), vous pouvez trouver de nombreuses autres \u00e9tudes infirmant cette \u00e9l\u00e9vation du risque, voire qui d\u00e9montrent justement une baisse de risque lors de la prise d\u2019hormones. Encore mieux, la quasi-totalit\u00e9 des \u00e9tudes portant sur des traitements aux hormones sexuelles administr\u00e9s \u00e0 des femmes qui ont eu un cancer du sein et \u00e0 des hommes qui ont pr\u00e9sent\u00e9 un cancer de la prostate ont montr\u00e9 des effets soit neutres soit r\u00e9duisant les r\u00e9cidives et la mortalit\u00e9. Nous n\u2019avons connaissance que d\u2019une seule \u00e9tude (sur 27 tout de m\u00eame !) qui a montr\u00e9 un effet inverse d\u2019augmentation du risque de r\u00e9cidive du cancer du sein ! Et justement, le tr\u00e8s dangereux m\u00e9droxyprogest\u00e9rone, d\u00e9riv\u00e9 non bio-identique de synth\u00e8se de la progest\u00e9rone, y avait \u00e9t\u00e9 utilis\u00e9 ! Chez un patient ayant un cancer g\u00e9nital avanc\u00e9, une th\u00e9rapie aux hormones sexuelles bien conduite \u2013 sans \u00eatre le traitement miracle, bien s\u00fbr \u2013 peut prolonger la survie, et aussi am\u00e9liorer la qualit\u00e9 de vie.<br \/>\nQuelques recommandations s\u2019imposent pour diminuer le risque de cancer lors de traitements hormonaux :<\/p>\n<ol>\n<li>Se faire suivre par un m\u00e9decin exp\u00e9riment\u00e9 en th\u00e9rapeutiques hormonales<\/li>\n<li>Prendre autant que possible les pr\u00e9parations hormonales les plus \u00ab naturelles\u00bb disponibles sur le march\u00e9, c&rsquo;est-\u00e0-dire les pr\u00e9parations qui contiennent des hormones de structure chimique identique \u00e0 celle des hormones naturellement pr\u00e9sentes dans le corps humain, ou qui se rapprochent le plus possible de cette structure naturelle. Les quelques accidents (tumeurs du foie, du rein, du col de l\u2019ut\u00e9rus, etc.) survenus au d\u00e9but des ann\u00e9es soixante et soixante-dix ont \u00e9t\u00e9 dus \u00e0 des traitements avec hormones artificielles, invent\u00e9es par l\u2019homme. C\u2019est le cas par exemple des d\u00e9riv\u00e9s d\u2019hormone m\u00e2le qui provoquent des tumeurs du foie, comme les anabolisants avec une structure 17-m\u00e9thyl\u00e9e, ou de l\u2019\u0153strog\u00e8ne de synth\u00e8se stilbestriol qui provoque des anomalies de l\u2019ut\u00e9rus et du vagin chez les filles n\u00e9es de m\u00e8res trait\u00e9es pendant leur grossesse avec ce produit, augmentant ainsi chez ces filles le risque de faire un cancer g\u00e9nital. Ces produits artificiels imitent mal la structure naturelle de nos propres hormones humaines. Le corps humain n\u2019y est pas suffisamment pr\u00e9par\u00e9. Heureusement, les firmes pharmaceutiques ont depuis longtemps retir\u00e9 les substances les plus toxiques du march\u00e9 comme celles mentionn\u00e9es ci-dessus, mais il en reste quelques-unes en pharmacie comme le m\u00e9droxyprogest\u00e9rone ac\u00e9tate, d\u00e9riv\u00e9 de la progest\u00e9rone.<\/li>\n<li>Suivre un traitement \u00e9quilibr\u00e9, c\u2019est-\u00e0-dire prendre un traitement o\u00f9 les hormones sont \u00e9quilibr\u00e9es entre elles. Ce juste \u00e9quilibre est crucial pour le bon d\u00e9roulement d\u2019une th\u00e9rapie aux hormones f\u00e9minines. La prise d\u2019\u0153stradiol naturel n\u00e9cessite d\u2019\u00eatre obligatoirement contrebalanc\u00e9e par une prise de progest\u00e9rone, de pr\u00e9f\u00e9rence naturelle ou bio-identique ou, \u00e0 d\u00e9faut, d\u2019un progestatif de structure tr\u00e8s proche comme la dydrogest\u00e9rone (Duphaston\u00ae). Pourquoi ? Parce que si des \u0153strog\u00e8nes sont pris sans progest\u00e9rone, le risque de cancer de l\u2019endom\u00e8tre augmente de cinq \u00e0 sept fois ! Le cancer de l\u2019endom\u00e8tre touche la couche interne de l\u2019ut\u00e9rus et est le seul cancer dont les scientifiques ont prouv\u00e9 de fa\u00e7on incontestable qu&rsquo;il est favoris\u00e9 par l\u2019administration d\u2019hormones, les \u0153strog\u00e8nes. Mais l\u2019addition de quelques milligrammes de progest\u00e9rone annule ce risque accru. Pour cette raison, les femmes qui ont gard\u00e9 leur ut\u00e9rus doivent toujours prendre de la progest\u00e9rone si elles prennent des \u0153strog\u00e8nes. Il est recommand\u00e9 aussi aux femmes ayant subi une ablation de l\u2019ut\u00e9rus (hyst\u00e9rectomie) de prendre de la progest\u00e9rone, et pas seulement des \u0153strog\u00e8nes contrairement \u00e0 une id\u00e9e largement r\u00e9pandue chez les gyn\u00e9cologues. Pour de nombreuses autres raisons, la progest\u00e9rone micronis\u00e9e ou son d\u00e9riv\u00e9 le plus proche sont n\u00e9cessaires chez ces femmes, particuli\u00e8rement pour \u00e9viter le gonflement excessif des seins et du ventre (caus\u00e9 par accumulation d\u2019eau) et pour calmer la nervosit\u00e9, l\u2019anxi\u00e9t\u00e9, le sommeil agit\u00e9, etc., qui sont des effets provoqu\u00e9s par l\u2019administration d\u2019\u0153strog\u00e8nes seuls. La progest\u00e9rone peut aussi diminuer chez ces femmes le risque de cancer du sein. Retenez qu\u2019il faut \u00e0 tout prix \u00e9viter que les seins gonflent douloureusement lors d\u2019un traitement aux hormones f\u00e9minines, car ce signe, qui est d\u00fb \u00e0 un exc\u00e8s d\u2019\u0153strog\u00e8ne et \u00e0 un manque de progest\u00e9rone, est associ\u00e9 \u00e0 un risque accru de cancer du sein : deux \u00e0 quatre fois plus ! Augmentez dans ce cas la dose de progest\u00e9rone et diminuez \u00e9ventuellement la dose d\u2019\u0153stradiol.<\/li>\n<li>\u00c9viter le surdosage. Le corps n\u2019est pas fait pour le dopage qui instaure une autre sorte de d\u00e9s\u00e9quilibre. Comme pour tout, un juste milieu doit \u00eatre trouv\u00e9 : ni trop, ni trop peu de suppl\u00e9ments hormonaux.<br \/>\n<strong>En prenant des traitements hormonaux bien conduits, il est tout \u00e0 fait possible de limiter les frais de sant\u00e9 \u00e0 long terme.<\/strong> Faire des bilans de sant\u00e9 r\u00e9guliers et suivre un ou plusieurs traitements hormonaux pour corriger les carences hormonales permet non seulement d\u2019\u00eatre au mieux de sa forme physique, mais peut aussi s\u2019av\u00e9rer \u00e9conomiquement int\u00e9ressant. Premi\u00e8rement parce que l\u2019on ne d\u00e9veloppe pas ou pas encore de maladies graves qui sont toujours co\u00fbteuses en m\u00e9dicaments, et deuxi\u00e8mement parce que la productivit\u00e9 professionnelle est optimis\u00e9e, souvent pour longtemps, ce qui se traduit g\u00e9n\u00e9ralement par de meilleures rentr\u00e9es financi\u00e8res. Tenter de faire des \u00e9conomies sur votre sant\u00e9 en \u00e9vitant les traitements hormonaux ou nutritionnels se r\u00e9v\u00e8le \u00eatre souvent une mauvaise fa\u00e7on de faire des \u00e9conomies car vous risquez surtout de vous exposer \u00e0 la d\u00e9gradation progressive de votre sant\u00e9, avec un risque accru de d\u00e9velopper des maladies cardiaques, du diab\u00e8te sucr\u00e9, de l&rsquo;ost\u00e9oporose, un cancer, la maladie d&rsquo;Alzheimer, etc.<\/li>\n<\/ol>\n<p><\/div><div class=\"title_code\">Comment les traitements hormonaux peuvent-ils contribuer \u00e0 r\u00e9duire le risque de d\u00e9veloppement ou de progression de maladies cardiaques et vasculaires ?<\/div>\n        <div class=\"content_code\"><br \/>\nLes maladies cardiovasculaires sont la premi\u00e8re cause de mort chez l\u2019adulte \u00e2g\u00e9. De nombreuses publications scientifiques ont d\u00e9montr\u00e9 les effets protecteurs consid\u00e9rables pour le c\u0153ur et les art\u00e8res des traitements \u00e0 l\u2019hormone de croissance, \u00e0 la DHEA, \u00e0 la m\u00e9latonine, aux hormones thyro\u00efdiennes (\u00e0 dose raisonnable), \u00e0 l\u2019\u0153stradiol, \u00e0 la testost\u00e9rone, \u00e0 l\u2019insuline (aux doses appropri\u00e9es), etc.<br \/>\nLa plupart de ces hormones prot\u00e8gent contre les maladies cardiovasculaires en am\u00e9liorant l\u2019\u00e9tat de la paroi art\u00e9rielle, lib\u00e9rant les art\u00e8res de l\u2019accumulation de cholest\u00e9rol oxyd\u00e9 et donc d\u2019ath\u00e9roscl\u00e9rose (vieillissement des art\u00e8res). Eh oui ! L\u2019ath\u00e9roscl\u00e9rose est r\u00e9versible partiellement ou totalement par des traitements hormonaux. Les mesures des parois art\u00e9rielles par ultrasons sur des patients trait\u00e9s aux hormones susmentionn\u00e9es sont presque syst\u00e9matiquement meilleures, de 10 \u00e0 20 ou 30 ans m\u00eame plus jeunes que leur \u00e2ge r\u00e9el ! Les hormones thyro\u00efdiennes stimulent l\u2019\u00e9vacuation de produits de d\u00e9chets qui s\u2019accumulent dans la paroi des vaisseaux sanguins lors d\u2019insuffisance thyro\u00efdienne. L\u2019hormone de croissance et la testost\u00e9rone, l\u2019hormone m\u00e2le, tonifient la paroi musculaire, composante majeure des vaisseaux sanguins et augmentent son \u00e9lasticit\u00e9, ce qui permet \u00e0 cette paroi de s\u2019adapter mieux \u00e0 la pression sanguine sans l\u2019augmenter excessivement. La m\u00e9latonine, DHEA, la testost\u00e9rone et l\u2019hormone de croissance rendent le sang plus fluide. Cette fluidit\u00e9 accrue du sang permet d\u2019\u00e9viter de r\u00e9duire les thromboses, ces caillots de sang qui se forment \u00e0 l\u2019int\u00e9rieur de vaisseaux sanguins et qui peuvent dangereusement ralentir le passage du sang et m\u00eame le bloquer. Ces hormones agissent sur le sang sans jamais le rendre trop fluide comme le font facilement les anticoagulants, provoquant des h\u00e9matomes isol\u00e9s un peu partout et dans le corps lors du moindre surdosage. Les hormones thyro\u00efdiennes, par contre, rendent le sang moins fluide en stimulant la production dans le foie de facteurs (prot\u00e9ines) de coagulation. Elles le font \u00e9galement sans augmenter le risque de rendre le sang trop coagulant.<\/p>\n<p><\/div><div class=\"title_code\">Comment les traitements hormonaux peuvent-ils augmenter la r\u00e9sistante aux infections ?<\/div>\n        <div class=\"content_code\"><br \/>\nPlusieurs traitements hormonaux r\u00e9veillent l\u2019immunit\u00e9 dormante de personnes affaiblies. Les hormones thyro\u00efdiennes, la thymosine-alpha-1 (hormone du thymus), l\u2019hormone de croissance, la DHEA (d\u00e9hydro\u00e9piandrost\u00e9rone), l\u2019\u0153stradiol, et m\u00eame le cortisol \u00e0 petites doses stimulent (parfois m\u00eame assez fortement) l\u2019immunit\u00e9. Typiquement, l\u2019enfant qui souffre d\u2019insuffisance en hormones thyro\u00efdiennes pr\u00e9sente des infections r\u00e9currentes, tout l\u2019hiver par exemple. Le traitement aux hormones thyro\u00efdiennes r\u00e9duit souvent fortement cette tendance. Bien trait\u00e9 par ces hormones, il n\u2019est pas rare de le voir passer l\u2019hiver sans aucune infection.<\/p>\n<p><\/div><div class=\"title_code\">Comment les traitements hormonaux peuvent-ils contribuer \u00e0 \u00e9viter ou \u00e0 att\u00e9nuer le diab\u00e8te?<\/div>\n        <div class=\"content_code\"><br \/>\nLe diab\u00e8te est une maladie o\u00f9 le sucre s\u2019accumule dans le sang, le rendant plus visqueux, plus collant, moins apte \u00e0 fournir aux cellules les nutriments essentiels \u00e0 leur bon fonctionnement. Cette accumulation de sucre est due soit \u00e0 l\u2019absence ou d\u00e9ficience en insuline (l\u2019hormone s\u00e9cr\u00e9t\u00e9e par le pancr\u00e9as), appel\u00e9e <strong>diab\u00e8te de type 1<\/strong>, soit \u00e0 une r\u00e9sistance du corps \u00e0 l\u2019insuline, appel\u00e9e diab\u00e8te de type 2. Dans le<strong> diab\u00e8te de type 2<\/strong>, l\u2019insuline peut \u00eatre tr\u00e8s \u00e9lev\u00e9e dans le sang, mais pas efficace. Plusieurs traitements hormonaux autres que l\u2019insuline peuvent agir favorablement pour r\u00e9duire la fr\u00e9quence ou la gravit\u00e9 du diab\u00e8te.<br \/>\n<strong>Le traitement aux hormones thyro\u00efdiennes<\/strong> am\u00e9liore la perfusion sanguine au niveau du pancr\u00e9as et stimule la s\u00e9cr\u00e9tion d\u2019insuline. Une \u00e9tude a montr\u00e9 que, chez les diab\u00e9tiques, le traitement thyro\u00efdien am\u00e9liore toutes les plaintes et tous signes physiques qui accompagnent le diab\u00e8te, sauf qu\u2019ils semblent peu efficaces \u00e0 am\u00e9liorer notablement le taux du sucre.<br \/>\n<strong>Le traitement \u00e0 l\u2019hormone m\u00e2le, la testost\u00e9rone,<\/strong> peut chez l\u2019homme inverser la gangr\u00e8ne (due \u00e0 une ath\u00e9roscl\u00e9rose \u2013 vieillissement des art\u00e8res \u2013 prononc\u00e9e) qui peut survenir dans les cas s\u00e9v\u00e8res de diab\u00e8te.<br \/>\n<strong>Le gel transdermique<\/strong> (appliqu\u00e9 sur la peau) <strong>d\u2019\u0153stradiol bio-identique<\/strong> (dont la structure mol\u00e9culaire est la m\u00eame que la structure de l\u2019hormone humaine) am\u00e9liore la capacit\u00e9 du pancr\u00e9as \u00e0 bien r\u00e9agir aux fluctuations du taux de sucre dans le sang, alors que les \u0153strog\u00e8nes prises en pilule, surtout sous forme non bio-identique (qui n\u2019ont pas la structure identique \u00e0 celle de l\u2019hormone humaine naturelle) et associ\u00e9es avec un progestatif (progest\u00e9rone non humaine non bioidentique), peuvent provoquer l\u2019inverse, soit des effets favorisant le d\u00e9veloppement du diab\u00e8te.<\/p>\n<p><\/div><div class=\"title_code\">Les traitements hormonaux peuvent-ils nous aider \u00e0 \u00e9viter de d\u00e9velopper la maladie d\u2019Alzheimer et d\u2019autres maladies du 12\/01\/2016 ou r\u00e9duire notre risque de les d\u00e9velopper ?<\/div>\n        <div class=\"content_code\"><br \/>\nLa maladie d\u2019Alzheimer est la forme de d\u00e9mence la plus fr\u00e9quente. Elle survient chez pr\u00e8s de 10 % des hommes et des femmes au-dessus de 65 ans. Son d\u00e9veloppement semble \u00eatre favoris\u00e9 par des carences hormonales. Citons parmi les causes hormonales favorisantes les d\u00e9ficits en \u0153stradiol, en hormones thyro\u00efdiennes, en testost\u00e9rone, en somatom\u00e9dine C, en DHEA, en m\u00e9latonine, en insuline, en vasopressine, pr\u00e9gn\u00e9nolone, etc. Le taux de ces hormones est en g\u00e9n\u00e9ral plus bas dans le sang et le liquide c\u00e9phalo-rachidien (le liquide dans lequel baignent le cerveau et les nerfs de la moelle \u00e9pini\u00e8re) de patients atteints de la maladie d\u2019Alzheimer. Ces hormones ont une influence favorable sur les neurones. La protection qu\u2019elles offrent contre \u00abl\u2019Alzheimer \u00bb commence \u00e0 \u00eatre d\u00e9montr\u00e9e pour les \u0153strog\u00e8nes, la testost\u00e9rone, et la vasopressine.<br \/>\nUne \u00e9tude a montr\u00e9, par exemple, que les femmes qui prennent des hormones f\u00e9minines apr\u00e8s la m\u00e9nopause ont huit fois moins de risque de d\u00e9velopper la maladie d\u2019Alzheimer que celles qui n\u2019ont rien pris !<\/p>\n<p><\/div><div class=\"title_code\">Les traitements hormonaux peuvent-ils contribuer \u00e0 nous garder \u00e9panouis en famille et dans la soci\u00e9t\u00e9 ?<\/div>\n        <div class=\"content_code\"><br \/>\nPlusieurs traitements hormonaux rendent plus sociable et peuvent renforcer les liens familiaux et sociaux. C\u2019est le cas de la<strong> th\u00e9rapie \u00e0 l\u2019ocytocine<\/strong> qui rend des personnes r\u00e2leuses et asociales (parce que carenc\u00e9es en cette hormone) plus ouvertes aux autres, plus aimantes et cordiales, et moins facilement d\u00e9rang\u00e9es par les autres. La carence importante en hormone de croissance tend aussi \u00e0 clo\u00eetrer une personne chez elle, tant elle voit les autres et le monde ext\u00e9rieur comme une source d\u2019angoisse et d\u2019\u00e9puisement. Le <strong>traitement \u00e0 l\u2019hormone de croissance<\/strong> r\u00e9tablit cette sociabilit\u00e9 et l\u2019ouverture aux autres en calmant cette angoisse et en redonnant l\u2019\u00e9nergie n\u00e9cessaire pour faire face aux situations sociales. Les hormones sexuelles sont les hormones de l\u2019amour. Un traitement aux hormones sexuelles augmente l\u2019attraction \u2013 sentimentale mais aussi purement sexuelle \u2013 mutuelle entre les partenaires d\u2019un couple. La carence en cortisol peut rendre une personne en situation de stress irritable, m\u00e9fiante, accusatrice et querelleuse, voire parfois carr\u00e9ment m\u00e9chante en rentrant dans des crises de nervosit\u00e9 caus\u00e9es par des d\u00e9charges d\u2019adr\u00e9naline. L\u2019adr\u00e9naline est secr\u00e9t\u00e9e pour compenser le d\u00e9ficit en cortisol mais peut \u2013 quand le pic d\u2019adr\u00e9naline est fort \u00e9lev\u00e9 \u2013 rendre insens\u00e9, follement agressif ou anxieux pendant une \u00e0 deux minutes. Le simple<strong> traitement au cortisol<\/strong> ou \u00e0 un de ses d\u00e9riv\u00e9s efface cette irritabilit\u00e9 et nervosit\u00e9 inutiles. Ainsi, avec un meilleur \u00e9quilibre hormonal, il est plus facile de s\u2019ouvrir aux autres, \u00e0 votre conjoint, aux membres de votre famille, aux amis et connaissances.<br \/>\nDe nombreux couples en crise r\u00e9ussissent \u00e0 prendre un nouveau d\u00e9part lors de traitements hormonaux et nutritionnels bien conduits, m\u00eame si un seul des deux ou les deux ensemble a\/ont \u00e9t\u00e9 trait\u00e9(s) par hormones et se retrouve(en)t mieux dans sa\/leur peau. Car gare aux couples o\u00f9 les deux conjoints ont des d\u00e9ficiences hormonales s\u00e9v\u00e8res ! Ils ont beaucoup de difficult\u00e9s \u00e0 s\u2019entendre car ils sont parasit\u00e9s par les sympt\u00f4mes de carence hormonale, et pour retrouver une bonne entente, les deux doivent rapidement rem\u00e9dier \u00e0 leurs carences.<\/p>\n<p><\/div><div class=\"title_code\">Pourquoi attacher de l\u2019importance \u00e0 obtenir une apparence physique plus jeune lors de la prise de traitements hormonaux ?<\/div>\n        <div class=\"content_code\"><br \/>\nQuelques patients s\u2019empressent de me dire \u00e0 la consultation qu\u2019ils ne souhaitent pas rajeunir, mais seulement se sentir mieux. Pourtant l\u2019un ne va pas sans l\u2019autre.<strong> Un traitement hormonal<\/strong> bien conduit chez une personne carenc\u00e9e <strong>am\u00e9liore tr\u00e8s souvent le physique \u00e0 c\u00f4t\u00e9 de l\u2019\u00e9tat physique<\/strong>. Et comme l\u2019apparence physique refl\u00e8te la sant\u00e9, si la sant\u00e9 s\u2019am\u00e9liore, ce progr\u00e8s se lit sur le visage et sur le corps.<br \/>\nLe m\u00e9decin doit <strong>chercher \u00e0 obtenir un visage et un corps plus jeunes chez son patient par l\u2019hormonoth\u00e9rapie<\/strong>, car cela repr\u00e9sente pour lui la marque visible de l\u2019efficacit\u00e9 du traitement.<br \/>\nChaque hormone produit un effet diff\u00e9rent sur le corps. La carence en hormones thyro\u00efdiennes, par exemple, permet \u00e0 des d\u00e9chets (mucopolysaccharides) de s\u2019accumuler entre les cellules, ce qui fait gonfler les tissus (donnant un \u0153d\u00e8me appel\u00e9 myx\u0153d\u00e8me). Le <strong>traitement thyro\u00efdien<\/strong> affine le visage et les mollets en acc\u00e9l\u00e9rant l\u2019\u00e9limination des d\u00e9chets entre les cellules. La th\u00e9rapie permet de perdre plus facilement les kilos superflus.<br \/>\nComme les reins et la circulation fonctionnent plus vite et mieux sous hormones thyro\u00efdiennes, les personnes qui gonflent des pieds et des chevilles d\u00e9gonflent \u00e0 ces endroits.<br \/>\nD\u2019autres hormones peuvent aussi embellir et rajeunir la silhouette. Les <strong>traitements aux androg\u00e8nes<\/strong> (hormones m\u00e2les) et aux <strong>hormones de croissance<\/strong> rendent le corps plus muscl\u00e9 et ferme, diminuant ou \u00e9liminant l\u2019ob\u00e9sit\u00e9 abdominale et la cellulite. Les muscles des bras se raffermissent, inversant le rel\u00e2chement musculaire d\u00fb \u00e0 l\u2019\u00e2ge et qui est en fait principalement caus\u00e9 par le manque de ces hormones. Les grosses rides du visage (comme celles du front et celles qui vont de la base du nez au coin des l\u00e8vres appel\u00e9es \u00ab plis naso-labiaux \u00bb) et le rel\u00e2chement des joues s\u2019estompent sous traitement \u00e0 l\u2019hormone de croissance. Les rides au-dessus des l\u00e8vres, si visibles chez les femmes m\u00e9nopaus\u00e9es, s\u2019effacent lors du <strong>traitement aux \u0153strog\u00e8nes et androg\u00e8nes<\/strong> parce qu\u2019elles apparaissent surtout \u00e0 cause du manque d\u2019hormones sexuelles. Les tout petits plis ou rides minuscules sur les joues et sous les yeux ainsi que celles plus profondes situ\u00e9es au coin ext\u00e9rieur des yeux diminuent fortement et peuvent m\u00eame dispara\u00eetre lors d\u2019un <strong>traitement \u00e0 la vasopressine<\/strong> (l\u2019hormone qui retient l\u2019eau dans la peau) et accessoirement \u00e0 la<strong> fludrocortisone<\/strong>, le d\u00e9riv\u00e9 synth\u00e9tique de l\u2019aldost\u00e9rone (hormone qui retient l\u2019eau dans le corps).<br \/>\n\u00c0 l\u2019oppos\u00e9,<strong> l\u2019administration de cortisol et d\u2019insuline<\/strong> chez les personnes qui en manquent aide \u00e0 combler les joues creuses et la minceur excessive du corps. Cependant, chez les personnes ob\u00e8ses, la th\u00e9rapie au cortisol peut avoir l\u2019effet inverse, entra\u00eenant un amaigrissement en diminuant l\u2019app\u00e9tit pour ceux qui \u00e9vitent les sucreries et les c\u00e9r\u00e9ales.<\/p>\n<p><\/div><div class=\"title_code\">Les traitements hormonaux peuvent-ils nous aider \u00e0 rester professionnellement et sportivement actifs ?<\/div>\n        <div class=\"content_code\"><br \/>\nDes traitements hormonaux peuvent aider \u00e0 <strong>poursuivre une profession<\/strong> passionnante ou dont on a \u00e9conomiquement besoin. Elles le font en \u00e9levant le niveau d\u2019\u00e9nergie (production et utilisation plus grande d\u2019ATP et NADPH, les mol\u00e9cules d\u2019\u00e9nergie de notre corps). Certains de ces traitements hormonaux peuvent consid\u00e9rablement augmenter la r\u00e9sistance au stress, <strong>rendant le travail plus facile \u00e0 g\u00e9rer<\/strong> dans les situations difficiles. C\u2019est le cas du cortisol et de l\u2019hormone de croissance, qui d\u2019une part stimulent le syst\u00e8me nerveux parasympathique (celui qui nous calme et nous rend ainsi moins inquiets), et d\u2019autre part augmentent le taux de sucre dans le sang, apportant plus d\u2019\u00e9nergie aux cellules en situation de stress. Le traitement au cortisol rend en g\u00e9n\u00e9ral plus combatif, stimule l\u2019envie d\u2019affronter les probl\u00e8mes, alors que le traitement \u00e0 l\u2019hormone de croissance permet d\u2019y voir plus clair dans les situations compliqu\u00e9es et de trouver des solutions. De plus, l\u2019hormonoth\u00e9rapie correctement appliqu\u00e9e peut rendre <strong>le sport<\/strong> et d\u2019autres loisirs plus faciles gr\u00e2ce \u00e0 un niveau \u00e9lev\u00e9 d\u2019\u00e9nergie et une humeur plus positive. Des traitements aux androg\u00e8nes et \u00e0 l\u2019hormone de croissance facilitent la (re)musculation et aident \u00e0 la pratique du sport. \u00c0 noter que lors d\u2019une carence s\u00e9v\u00e8re en hormone de croissance, le patient est incapable de travailler et de pratiquer un sport car il est tout le temps \u00e9puis\u00e9. Le simple traitement \u00e0 l\u2019hormone de croissance rend \u00e0 la personne sa capacit\u00e9 professionnelle et sportive.<\/p>\n<p><\/div><div class=\"title_code\">Traitement hormonal : prise de poids ind\u00e9sirable : quelle en est la cause ?<\/div>\n        <div class=\"content_code\"><br \/>\nSi votre choix de nourriture (alimentation du type \u00ab Pal\u00e9olithique \u00bb faite de fruits, l\u00e9gumes, viande poisson et poulet) et de boissons (pas de caf\u00e9, ni d\u2019alcool) est bonne, il est possible, soit que votre app\u00e9tit a augment\u00e9 et que vous avez mang\u00e9 beaucoup plus qu\u2019auparavant, soit que vous avez eu un mode de vie beaucoup plus s\u00e9dentaire. <strong>Les traitements hormonaux vous rendent beaucoup plus sensible qu\u2019auparavant \u00e0 la qualit\u00e9 des aliments que vous consommez<\/strong>. Si vous avez l\u2019habitude de consommer des aliments riches en glucides (sucreries, p\u00e2tes, pain, muesli, graisses cuites, etc.), les traitements hormonaux vont favoriser une prise de poids. Si par contre, vous mangez les aliments \u00ab pal\u00e9o \u00bb, vous perdez plus facilement du poids.<br \/>\nMes conseils pour perdre du poids :<\/p>\n<ul>\n<li>Faire 30\u2019 d\u2019exercice physique par jour ; plus efficace que 60\u2019 par jour car quand vous faites davantage (trop) d\u2019exercice, l\u2019app\u00e9tit augmente et la plupart des personnes mangent plus\u2026 et donc trop ;<\/li>\n<li>Suivre ou continuer le r\u00e9gime pal\u00e9o ;<br \/>\nSi vous tol\u00e9rez bien les hormones thyro\u00efdiennes \u2013 il est tr\u00e8s probable que votre taux est encore insuffisant \u2013 augmentez progressivement votre dose de 75 mg \u00e0 120 mg \/jour d\u2019extrait thyro\u00efdien. Mais faites bien attention qu\u2019aucun signe de surdosage ne survienne (en ce cas r\u00e9duisez la dose) ;<\/li>\n<li>Avez-vous commenc\u00e9 \u00e0 prendre le traitement \u00e0 l\u2019hormone de croissance comme pr\u00e9vu dans votre programme de m\u00e9dication ? Si ce n\u2019est pas le cas, commencez-le car il favorise la perte de graisse et le renforcement musculaire. Une perte totale de poids de 2 kg est souvent obtenue sous ce traitement ;<\/li>\n<li>Prenez-vous bien le traitement \u00e0 l\u2019hydrocortisone \u00e0 la dose de 20 mg\/ jour, ou bien prenez-vous davantage ? Dans ce dernier cas, ramenez la dose \u00e0 15-20 mg\/jour ;<\/li>\n<li>De toute fa\u00e7on, il y a une (nouvelle) solution \u00e0 long terme au probl\u00e8me de l\u2019app\u00e9tit et du poids :\n<ul>\n<li>prendre des probiotiques (au moins &gt; 5 milliards de germes par g\u00e9lule) : 3 x \/ jour avant chaque repas ;<\/li>\n<li>prendre des enzymes digestives \u00e0 chaque repas (double dose pendant les repas lourds) : demandez de la pancr\u00e9atine (enzymes pancr\u00e9atiques) \u00e0 votre pharmacien (au moins 200 \u00e0 300 mg\/comprim\u00e9) ;<\/li>\n<li>boire 3 verres d\u2019eau (\u00bd litre) 10-30 minutes avant chaque repas ;<\/li>\n<li>manger peu (que des l\u00e9gumes) ou pas apr\u00e8s 18h : ne mangez les viandes ou autres prot\u00e9ines qu\u2019au petit d\u00e9jeuner et d\u00e9jeuner. Lorsque vous mangez de grosses quantit\u00e9s de prot\u00e9ines le soir, celles-ci ralentissant votre activit\u00e9 thyro\u00efdienne (en ralentissant la conversion de la peu active hormone thyro\u00efdienne T4 en tr\u00e8s active T3) pendant toute la nuit ce qui ne vous permet pas de perdre du poids pendant se temps, mais au contraire de vous faire gonfler au visage et au ventre.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p><\/div><div class=\"title_code\">La vitamine A est-elle toxique ? <\/div>\n        <div class=\"content_code\"><br \/>\nBeaucoup de patients se demandent si la prise d\u2019un suppl\u00e9ment de vitamine A pourrait \u00eatre toxique. Quand ils vont voir sur internet ou lorsqu\u2019ils interrogent des m\u00e9decins, ces patients d\u00e9couvrent toutes sortes d\u2019effets secondaires ind\u00e9sirables li\u00e9s \u00e0 la vitamine A, allant des malformations f\u0153tales jusqu\u2019aux troubles du foie. Qu\u2019en est-il r\u00e9ellement ? Car il ne faut pas oublier que la vitamine A pr\u00e9sente surtout des effets b\u00e9n\u00e9fiques majeurs : peau et muqueuse moins s\u00e8ches, stimulation non n\u00e9gligeable de la production d\u2019hormones sexuelles, protection importante contre de nombreux de cancers y compris ceux du sein et de la prostate. Des \u00e9tudes en laboratoire sur des cellules canc\u00e9reuses montrent m\u00eame dans certains cas que la vitamine A peut rendre certaines cellules canc\u00e9reuses \u00e0 nouveau non canc\u00e9reuses, ou moins canc\u00e9reuses, autrement dit inverser le processus du cancer. Pour \u00e9viter toute confusion, il faut savoir qu\u2019il existe deux types de vitamine A et deux formes diff\u00e9rentes de l\u2019administrer. Il s\u2019agit donc de choisir le meilleur type et la meilleure forme de vitamine A pour garantir la s\u00e9curit\u00e9 du traitement, sans oublier de toujours donner la dose appropri\u00e9e. Ces quelques choix peuvent faire toute la diff\u00e9rence entre effets b\u00e9n\u00e9fiques et effets ind\u00e9sirables. On trouve deux types de vitamine A : la structure naturelle ou les d\u00e9riv\u00e9s de synth\u00e8se. Les d\u00e9riv\u00e9s de synth\u00e8se de la vitamine A contiennent des produits comme l\u2019isotr\u00e9tino\u00efne, \u00e9galement appel\u00e9e tr\u00e9tino\u00efne. Ce produit utilis\u00e9 pour r\u00e9duire l\u2019acn\u00e9 et pour att\u00e9nuer les rides est fortement t\u00e9ratog\u00e8ne ; il provoque des malformations f\u0153tales et peut porter atteinte au foie.<br \/>\nCes risques importants nous poussent donc \u00e0 fortement conseiller la prise de vitamine A de structure naturelle, bien que son efficacit\u00e9 contre l\u2019acn\u00e9 et les rides soit moindre. Cette vitamine A de structure naturelle (ou bioidentique, c\u2019est-\u00e0-dire identique \u00e0 la structure de la vitamine A pr\u00e9sente dans le corps humain) peut \u00eatre administr\u00e9e sous deux formes. D\u2019une part, une forme hydrosoluble, soluble dans l\u2019eau, que le corps absorbe tr\u00e8s bien mais qui pr\u00e9sente une forte toxicit\u00e9 pour le foie, et d\u2019autre part, la vitamine A liposoluble, autrement dit soluble dans la graisse. Celle-ci est moins bien absorb\u00e9e mais peut \u00eatre prise \u00e0 haute dose (100.000 unit\u00e9s internationales par jour ou plus pendant de longues p\u00e9riodes de six \u00e0 douze mois) sans effets toxiques chez la grande majorit\u00e9 des patients. C\u2019est donc bien la forme liposoluble de la vitamine A de structure naturelle et non les d\u00e9riv\u00e9s de synth\u00e8se que je propose \u00e0 mes patients. Ce traitement se prend sous forme de perles huileuses de 10 000 \u00e0 50 000 unit\u00e9s internationales. Pour \u00e9viter les surdosages qui peuvent ab\u00eemer le foie et rendre la peau plus s\u00e8che, je recommande un dosage r\u00e9gulier de vitamine A dans le sang (s\u00e9rum).<\/p>\n<p><\/div><div class=\"title_code\">Peut-on prendre des doses tr\u00e8s \u00e9lev\u00e9es de vitamine D ?<\/div>\n        <div class=\"content_code\"><br \/>\nQuand on me demande si la vitamine D peut \u00eatre prise \u00e0 haute dose sans risque de toxicit\u00e9, je r\u00e9ponds qu\u2019il existe \u00e9galement plusieurs types de vitamine D. \u00c0 commencer par la vitamine D3 qui est la vitamine D typique des mammif\u00e8res. La vitamine D2 se retrouve \u00e9galement dans le sang humain, mais provient de l\u2019alimentation, notamment des l\u00e9gumes que nous consommons car la vitamine D2 se trouve majoritairement dans les plantes. Il existe \u00e9galement des vitamines D activ\u00e9es comme le alphacalcif\u00e9diol qui, \u00e0 des doses nettement plus basses (2 \u00b5g\/jour), donne des effets plus performants, mais peuvent \u00eatre potentiellement toxiques. Actuellement dans plusieurs pays du monde, des doses tr\u00e8s \u00e9lev\u00e9es de vitamines D3 sont donn\u00e9es pour inverser les maladies d\u00e9g\u00e9n\u00e9ratives comme la scl\u00e9rose multiple, le cancer, l\u2019ost\u00e9oporose ou le rhumatisme (entre 10 000 et 40000 unit\u00e9s internationales par jour, soit 250 \u00e0 1000 \u00b5g par jour) sans provoquer apparemment d\u2019effets ind\u00e9sirables. Une \u00e9tude de Kimball et collaborateurs a montr\u00e9 que gr\u00e2ce \u00e0 des doses de vitamine D allant jusqu\u2019\u00e0 40000 UI, on parvenait \u00e0 diminuer de moiti\u00e9 les l\u00e9sions de la scl\u00e9rose multiple. Ces doses \u00e9lev\u00e9es faisaient quadrupler le taux de vitamine D des patients (soit le double de la limite sup\u00e9rieure de r\u00e9f\u00e9rence du laboratoire) sans entra\u00eener d\u2019effets secondaires (tests h\u00e9patiques non perturb\u00e9s, calcium normal dans le sang).<br \/>\nCette vitamine D peut parfois \u00eatre donn\u00e9e sous forme d\u2019injection pour optimiser ses effets. D\u2019apr\u00e8s les m\u00e9decins ayant test\u00e9 cette m\u00e9thode, les r\u00e9sultats sont convaincants : inject\u00e9e, elle aurait un effet anti-inflammatoire et r\u00e9parateur important \u00e0 doses \u00e9lev\u00e9es. Il semble que le seuil de s\u00e9curit\u00e9 (ne pr\u00e9sentant aucun signe de danger pour le patient) soit de 10 000 UI par jour (ou 250 \u00b5g par jour) de vitamine D3 (voir figure 1).<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-708\" src=\"https:\/\/www.hertoghe.eu\/wp-content\/uploads\/vitamine-D.png\" alt=\"vitamine-D\" width=\"800\" height=\"516\" srcset=\"https:\/\/www.hertoghe.eu\/wp-content\/uploads\/vitamine-D.png 800w, https:\/\/www.hertoghe.eu\/wp-content\/uploads\/vitamine-D-300x194.png 300w, https:\/\/www.hertoghe.eu\/wp-content\/uploads\/vitamine-D-768x495.png 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><br \/>\nCependant, comme chaque personne a une absorption ou une utilisation particuli\u00e8re de la vitamine D en fonction de son organisme, il en r\u00e9sulte des taux diff\u00e9rents de vitamine D dans le sang. Il est donc recommand\u00e9 de v\u00e9rifier les taux sanguins pour s\u2019assurer que les doses soient suffisantes pour chacun. Je recommande des dosages r\u00e9guliers de vitamines D2 et D3 dans le sang tous les quatre \u00e0 six mois \u00e0 tous les patients prenant de hautes doses pour traiter une pathologie difficile. Le but \u00e9tant d\u2019arriver \u00e0 des taux de vitamine D dans le sang entre 50 et 125 ng par millilitre (voir figure 2), c\u2019est-\u00e0-dire une dose l\u00e9g\u00e8rement sup\u00e9rieure \u00e0 la limite de r\u00e9f\u00e9rence valable dans les pays ensoleill\u00e9s (l\u2019Espagne par exemple o\u00f9 la limit\u00e9 sup\u00e9rieure de vitamine D est de 100 ng\/mL ou 250 nmol\/L) ou m\u00eame largement sup\u00e9rieure \u00e0 la limite de r\u00e9f\u00e9rence dans les pays \u00e0 moindre ensoleillement (comme la Belgique o\u00f9 la limite sup\u00e9rieure de r\u00e9f\u00e9rence est g\u00e9n\u00e9ralement de 60 ng\/mL ou 150 nmol\/L !).<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-709\" src=\"https:\/\/www.hertoghe.eu\/wp-content\/uploads\/vitamine-D-2.png\" alt=\"vitamine-D-2\" width=\"800\" height=\"517\" srcset=\"https:\/\/www.hertoghe.eu\/wp-content\/uploads\/vitamine-D-2.png 800w, https:\/\/www.hertoghe.eu\/wp-content\/uploads\/vitamine-D-2-300x194.png 300w, https:\/\/www.hertoghe.eu\/wp-content\/uploads\/vitamine-D-2-768x496.png 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><br \/>\nIl faut n\u00e9anmoins \u00e9viter de d\u00e9passer les 150 ng par millilitre (375 nmol\/L) car cette dose pourrait provoquer une hypercalc\u00e9mie, c\u2019est-\u00e0-dire des taux excessifs de calcium avec calcifications (d\u00e9p\u00f4ts de calcium) \u00e9parpill\u00e9es dans le corps et calculs r\u00e9naux (lithiases). Le foie risque \u00e9galement de ne pas supporter ces doses \u00e9lev\u00e9es. Je recommande donc un suivi r\u00e9gulier par prise de sang v\u00e9rifiant le dosage de la vitamine D ainsi que des tests h\u00e9patiques pour d\u00e9tecter au plus t\u00f4t tout dosage trop \u00e9lev\u00e9 et toute anomalie du foie.<br \/>\nFigures 1 &amp; 2 : IOM (Institute of Medicine). Dietary Reference Intakes for Calcium and Vitamin D. The National<br \/>\nAcademies Press: Washington, DC, 2011 dans : Zittermann A, Prokop S, Gummert JF, B\u00f6rgermann J. Safety issues of vitamin D supplementation. Anticancer Agents Med Chem. 2013 Jan; 13(1):4-10. Review . (\u201cHypercalcemia, the hallmark of vitamin D intoxication, may only occur if circulating 25(OH)D levels are consistently above 375-500 nmol\/l. However, some observational studies indicate that already circulating 25(OH)D levels &gt; 125 nmol\/l are related to an increased morbidity and mortality risk. Therefore, the Institute of Medicine has set the UL for adults at 100 \u03bcg\/d, and the adequate circulating 25(OH)D level at 50 to 125nmol\/l.\u201d)<\/p>\n<p>&nbsp;<\/p>\n<p><\/div><div class=\"title_code\">Les effets de la carnitine sur la thyro\u00efde : La carnitine inhibe-t-elle les effets de T3 et T4 ?<\/div>\n        <div class=\"content_code\"><br \/>\nUn des m\u00e9decins de mon \u00e9quipe me pose cette question. Oui, la prise de carnitine ralentit la thyro\u00efde, comme toute prise d\u2019acide amin\u00e9 et de prot\u00e9ine (hormis la tyrosine qui est un pr\u00e9curseur aux hormones thyro\u00ef\u00acdiennes). La carnitine est un acide amin\u00e9 qui se retrouve dans la viande (d\u2019o\u00f9 le nom de \u00ab carne \u00bb, qui signifie \u00ab viande \u00bb en latin). Plus que tous les autres acides amin\u00e9s,<strong> la carnitine diminue la conversion de la peu active T4 en hormone thyro\u00efdienne T3 tr\u00e8s active<\/strong>. La carnitine est d\u2019ailleurs utilis\u00e9e pour traiter l\u2019exc\u00e8s d\u2019hormones thyro\u00efdiennes, l\u2019hyperthyro\u00efdie. Pour obtenir cet effet, faites progresser votre dose de 3 \u00e0 6 g\/jour, \u00e0 prendre le matin et \u00e9ventuellement aussi \u00e0 midi. Pas le soir car sinon la carnitine a tendance \u00e0 vous r\u00e9veiller.<\/p>\n<p><\/div><div class=\"title_code\">Les hormones sont-elles interdites dans certains pays ?<\/div>\n        <div class=\"content_code\"><br \/>\nPourquoi des hormones comme la m\u00e9latonine sont-elles interdites dans certains pays ? La Belgique, par exemple, a \u00e9t\u00e9 pendant longtemps le seul pays au monde \u00e0 l\u2019interdire. Une proc\u00e9dure juridique que j\u2019ai enclench\u00e9 avec une patiente montra l\u2018incongruit\u00e9 de cette mesure et a fait annuler la loi, permettant apr\u00e8s 8 ans de proc\u00e9dure, la vente de m\u00e9latonine en pharmacie. La m\u00e9latonine am\u00e9liore le sommeil et diminue le jet lag ou syndrome du d\u00e9calage horaire. De nombreuses exp\u00e9riences ont \u00e9t\u00e9 faites sur cette hormone, certaines \u00e0 doses tr\u00e8s \u00e9lev\u00e9es (plus de 1000 fois la quantit\u00e9 quotidiennement produite) sur des hommes et femmes volontaires, sans grave probl\u00e8me. Une dose l\u00e9tale (mortelle) n\u2019a jamais \u00e9t\u00e9 atteinte ou trouv\u00e9e.<br \/>\nDe plus, la m\u00e9latonine est une hormone qui se retrouve chez tout \u00eatre vivant (de l\u2019animal \u00e0 la bact\u00e9rie en passant par la plante), elle existerait m\u00eame depuis plus de trois milliards d\u2019ann\u00e9es sur Terre ! Une m\u00eame esp\u00e8ce de bact\u00e9ries que celle qui existe aujourd\u2019hui et qui contient de la m\u00e9latonine a en effet \u00e9t\u00e9 retrouv\u00e9e emprisonn\u00e9e dans des roches datant de trois milliards d\u2019ann\u00e9es ! Il semble donc que ce produit soit assez s\u00fbr et qu\u2019il ait fait ses preuves, m\u00eame s\u2019il est toujours plus sage de prendre cette hormone sous surveillance m\u00e9dicale car des effets de surdosage sont possibles.<br \/>\nLe cas de l\u2019interdiction de la m\u00e9latonine en Belgique est typique de la mani\u00e8re nonchalante ou maladroite d\u2019agir des autorit\u00e9s l\u00e9gales envers les traitements hormonaux. Scientifiquement et humainement, l\u2019interdiction ne se justifie pas. Mieux encore, la m\u00e9latonine est consid\u00e9r\u00e9e comme le meilleur et le moins risqu\u00e9 des somnif\u00e8res. Le gouvernement belge a \u00e9t\u00e9 s\u00e9v\u00e8rement condamn\u00e9 et oblig\u00e9 d\u2019annuler l\u2019interdiction de la m\u00e9latonine car le texte de loi l\u2019interdisant faisait faussement mention d\u2019une commission officielle des m\u00e9dicaments qui aurait statu\u00e9 sur la m\u00e9latonine. Cette \u00ab commission \u00bb aurait d\u00e9clar\u00e9 qu\u2019il n\u2019existait pas assez d\u2019\u00e9tudes scientifiques sur la s\u00e9curit\u00e9 et l\u2019efficacit\u00e9 permettant sa d\u00e9livrance, sans apporter les preuves de cette fausse affirmation (alors que dans la proc\u00e9dure pour le retrait de l\u2019interdiction j\u2019ai d\u00e9montr\u00e9 l\u2019inverse par la r\u00e9daction d\u2019un livre de r\u00e9f\u00e9rence de plus de 800 pages qui comprenait presque toutes les \u00e9tudes publi\u00e9es sur la m\u00e9latonine, plus de 4 000 r\u00e9f\u00e9rences scientifiques). Bien s\u00fbr, aucune commission ne s\u2019\u00e9tait r\u00e9unie sur ce sujet, le ministre avait agi de sa propre autorit\u00e9, donc ill\u00e9galement.<br \/>\nCe type d\u2019intervention incomp\u00e9tente et mensong\u00e8re \u00e9tait bas\u00e9 sur le pr\u00e9jug\u00e9 et l\u2019absence de concertation aupr\u00e8s de m\u00e9decins r\u00e9ellement exp\u00e9riment\u00e9s en m\u00e9latonine. Au-del\u00e0 du probl\u00e8me de la m\u00e9latonine, d\u2019autres traitements hormonaux essentiels peuvent ne pas \u00eatre officiellement autoris\u00e9s dans certains pays, voire carr\u00e9ment interdits.<br \/>\nC\u2019est le cas en Espagne, o\u00f9 la DHEA n\u2019est pas officiellement autoris\u00e9e. Ne pas autoriser une mol\u00e9cule aussi abondante dans le corps que la DHEA (vingt fois plus abondante dans le sang que n\u2019importe quelle autre hormone) et qui pr\u00e9sente un risque faible d\u2019effets secondaires et aucun effet dangereux (pour la sant\u00e9) n\u2019est-il pas absurde?<br \/>\nIci, \u00e0 nouveau, comme pour la m\u00e9latonine, c\u2019est l\u2019ignorance et l\u2019incomp\u00e9tence des services responsables qui sont \u00e0 la base de l\u2019interdiction de traitements hormonaux cruciaux pour une am\u00e9lioration de la sant\u00e9. Parfois, la cause est aussi plus pernicieuse: il arrive qu\u2019un lobbying pharmaceutique intervienne contre un traitement jug\u00e9 concurrentiel. C\u2019est probablement le cas pour la m\u00e9latonine dont la mise sur le march\u00e9 pouvait \u00eatre mal vue par les firmes qui vendent des somnif\u00e8res\u2026Quoiqu\u2019il en soit, aucune de ces interventions n\u2019est ou n\u2019\u00e9tait justifi\u00e9e pour interdire des traitements hormonaux indispensables \u00e0 la sant\u00e9.<\/p>\n<p><\/div><div class=\"title_code\">Les th\u00e9rapies hormonales et pro-\u00e2ge : existe-t-il suffisamment d\u2019\u00e9tudes scientifiques valables ?<\/div>\n        <div class=\"content_code\"><br \/>\nLe terme \u00ab pro-\u00e2ge \u00bb est ici utilis\u00e9 pour remplacer le terme plus n\u00e9gatif d\u2019\u00ab anti-\u00e2ge \u00bb car le but de cette m\u00e9decine n\u2019est pas d\u2019\u00eatre \u00ab anti \u00bb mais bien \u00ab pro \u00bb. Existe-t-il assez d\u2019\u00e9tudes scientifiques pour valider et autoriser les th\u00e9rapies anti-\u00e2ges et hormonales ? La r\u00e9ponse est oui. Les personnes, y compris les m\u00e9decins, qui disent qu\u2019il n\u2019existe pas assez d\u2019\u00e9tudes ne sont tout simplement pas all\u00e9es v\u00e9rifier l\u2019information. En r\u00e9alit\u00e9, de tr\u00e8s nombreuses \u00e9tudes s\u00e9rieuses ont \u00e9t\u00e9 publi\u00e9es dans des revues avec comit\u00e9s de lecture (peer review). Par exemple, sur la banque de donn\u00e9es Medline, chaque ann\u00e9e plus de 2000 nouvelles \u00e9tudes scientifiques s\u2019ajoutent pour l\u2019hormone de croissance (growth hormone, somatotropine), l\u2019IGF-1 (insulin-like, growth factor-1) ou la somatom\u00e9dine. La publication continuelle de nouvelles \u00e9tudes scientifiques est aussi le cas pour d\u2019autres th\u00e9rapies hormonales.<\/p>\n<p><\/div><div class=\"title_code\">Les traitements hormonaux ont-ils des effets prouv\u00e9s ? Sont-ils r\u00e9ellement efficaces ? existe-t-il suffisamment d\u2019\u00e9tudes scientifiques qui les soutiennent ?<\/div>\n        <div class=\"content_code\"><br \/>\nOui. Il existe pr\u00e8s de 600 000 \u00e9tudes r\u00e9pertori\u00e9es dans la grande banque de donn\u00e9es m\u00e9dicales et scientifiques Medline accessible sur Internet et qui reprend les principales \u00e9tudes m\u00e9dicales. Elle contient plus de 60 000 investigations scientifiques pour l\u2019hormone de croissance et la somatom\u00e9dine C (IGF-1), pr\u00e8s de 120 000 pour les hormones thyro\u00efdiennes, plus de 60 000 publications pour la testost\u00e9rone et les androg\u00e8nes, plus de 250 000 pour le cortisol et ses d\u00e9riv\u00e9s, pr\u00e8s de 15 000 pour la m\u00e9latonine et la glande pin\u00e9ale, plus de 10 000 pour la DHEA, 40 000 pour l\u2019insuline et le diab\u00e8te, 11 000 pour l\u2019aldost\u00e9rone ou son d\u00e9riv\u00e9 la fludrocortisone, et pr\u00e8s de 65 000 pour les \u0153strog\u00e8nes. Le \u00ab parent pauvre \u00bb est la pr\u00e9gn\u00e9nolone qui n\u2019a fait l\u2019objet que de 1 500 citations, dont approximativement 200 \u00e9tudes comportant son nom dans le titre.<br \/>\nPratiquement aucun m\u00e9dicament invent\u00e9 et brevet\u00e9 par une firme pharmaceutique ne peut se targuer d\u2019avoir \u00e9t\u00e9 investigu\u00e9 aussi souvent que chacune de ces hormones, la pr\u00e9gn\u00e9nolone except\u00e9e.<\/p>\n<p><\/div><div class=\"title_code\">Ne vaut-il pas mieux \u00e9viter tout traitement hormonal en attendant que les th\u00e9rapies hormonales soient mieux connues et que tous les m\u00e9decins se soient mis d\u2019accord ?<\/div>\n        <div class=\"content_code\"><br \/>\nEn d\u2019autres termes : ne vaut-il pas mieux s\u2019abstenir de tout traitement hormonal jusqu\u2019\u00e0 ce que tous les effets secondaires ou interactions soient connus et que tous les autres m\u00e9decins et institutions se soient mis d\u2019accord? On ne sait jamais\u2026<br \/>\n<strong>Non<\/strong>, ce n\u2019est pas parce que le corps m\u00e9dical au complet ne s\u2019est pas encore d\u00e9cid\u00e9 que l\u2019on doit priver une grande partie de la population (en particulier les personnes \u00e2g\u00e9es) de traitements hormonaux essentiels \u00e0 leur qualit\u00e9 de vie et \u00e0 leur sant\u00e9. La n\u00e9cessit\u00e9, l\u2019utilit\u00e9, le bien-fond\u00e9, les effets secondaires, les interactions, la prudence et la s\u00e9curit\u00e9 (si les directives sont bien suivies) des traitements hormonaux et nutritionnels ont d\u00e9j\u00e0 \u00e9t\u00e9 d\u00e9montr\u00e9s par des \u00e9tudes scientifiques rigoureuses et mis en \u00e9vidence par les m\u00e9decins pro-aging pour justifier leur utilisation. Les personnes \u00e2g\u00e9es en particulier n\u2019ont plus le temps d\u2019attendre. Du fait de leur \u00e2ge avanc\u00e9, elles risquent de ne plus \u00eatre l\u00e0 quand le corps m\u00e9dical aura reconnu le caract\u00e8re essentiel des traitements hormonaux pour la sant\u00e9 et se sera finalement prononc\u00e9 pour leur n\u00e9cessit\u00e9 et leur bien-fond\u00e9.<\/p>\n<p><\/div><div class=\"title_code\">La m\u00e9decine pro-aging ou reversing aging ne fait-elles pas de fausses promesses en visant le rajeunissement ou l\u2019att\u00e9nuation du vieillissement, choses impossibles \u00e0 l\u2019heure actuelle ? <\/div>\n        <div class=\"content_code\"><br \/>\nCertaines personnes qui n\u2019ont pas d\u2019exp\u00e9rience dans le domaine affirment que la m\u00e9decine pro-aging ne peut pas rajeunir (inverser le vieillissement), ni ralentir ou att\u00e9nuer le vieillissement, parce que ce sont des choses impossibles \u00e0 l\u2019heure actuelle. Elles affirment que pr\u00e9tendre le contraire serait faire de fausses promesses.<br \/>\nIl est vrai qu\u2019\u00e0 l\u2019heure actuelle les m\u00e9decins ne peuvent pas rajeunir d\u00e9finitivement et compl\u00e8tement un patient qui a d\u00e9pass\u00e9 soixante ans, ni enlever pour toujours toute forme de vieillissement chez lui, ni le garder jeune \u00e9ternellement. Je suis d\u2019accord : nous sommes encore loin de tout \u00e7a !<br \/>\nCertains aspects ou processus du vieillissement sont n\u00e9anmoins r\u00e9versibles, mais pas tous, ce qui fait que l\u2019on ne peut pas encore inverser le vieillissement de plus de 20 ans par exemple. On ne peut donc pas promettre monts et merveilles aux patients et la majorit\u00e9 des m\u00e9decins qui exercent cette discipline ne le fait pas et ne doit pas le faire! La m\u00e9decine n\u2019est pas encore assez performante. La patience et la retenue sont de mise. Bien s\u00fbr, les effets b\u00e9n\u00e9fiques des traitements hormonaux chez certains patients (et non pas la majorit\u00e9) sont parfois spectaculaires au d\u00e9but, mais jamais totalement rajeunissants. L\u2019enthousiasme des patients et des m\u00e9decins qui pratiquent cette m\u00e9decine visant la long\u00e9vit\u00e9 est stimul\u00e9, parfois excessivement, par ces quelques r\u00e9sultats spectaculaires. Ce n\u2019est pas une raison pour croire que tout est possible.<br \/>\nCependant cette m\u00e9decine progresse rapidement, et un jour, peut-\u00eatre proche, nous pourrons inverser le vieillissement chez une personne de 70 ans jusqu\u2019\u00e0 lui rendre son apparence et sa sant\u00e9 mentale et physique de ses 30 \u00e0 40 ans. Nous ne savons pas de quoi l\u2019avenir sera fait mais nous continuons les recherches et gardons \u00e0 l\u2019esprit ce but ultime de la m\u00e9decine reversing aging.<\/p>\n<p><\/div><div class=\"title_code\">Pourquoi existe-t-il des controverses sur les th\u00e9rapies hormonales utilis\u00e9es pour att\u00e9nuer le vieillissement ? <\/div>\n        <div class=\"content_code\"><br \/>\nLa plupart des traitements hormonaux sont donn\u00e9s pour corriger des carences hormonales, que ce soit en m\u00e9decine traditionnelle ou en m\u00e9decine pro-aging ou reversing aging. Cependant, les th\u00e9rapies hormonales pro-\u00e2ge engendrent des controverses parfois houleuses. Voici les raisons les plus communes.<\/p>\n<ol>\n<li>La fr\u00e9quence et la facilit\u00e9 apparentes avec lesquelles les traitements hormonaux sont donn\u00e9s<br \/>\nCompar\u00e9s aux autres disciplines m\u00e9dicales, les traitements hormonaux en m\u00e9decine pro-\u00e2ge sont donn\u00e9s <strong>aux patients plus facilement, en plus grand nombre, \u00e0 un \u00e2ge plus jeune, et chez des personnes qui ne semblent pas franchement malades<\/strong> (les d\u00e9tracteurs parlent souvent de \u00ab cocktail hormonal \u00bb). En effet, la m\u00e9decine pro-aging intervient pr\u00e9cocement, lorsque la baisse des taux hormonaux li\u00e9e \u00e0 l\u2019\u00e2ge est encore l\u00e9g\u00e8re et sans effets n\u00e9gatifs s\u00e9v\u00e8res. Il est alors encore temps d\u2019emp\u00eacher que les personnes tombent malades et vieillissent par manque d\u2019hormones. La m\u00e9decine traditionnelle, quant \u00e0 elle, s\u2019y prend souvent trop tard en ne traitant qu\u2019une partie des 2,5 % des patients qui ont un taux hormonal en dessous de la valeur statistique de r\u00e9f\u00e9rence. \u00c0 ce niveau, le taux hormonal a trop fortement baiss\u00e9 pour pouvoir tout corriger, laissant souvent des l\u00e9sions irr\u00e9versibles de maladie ou de vieillissement. <strong>Une bonne pr\u00e9vention est donc une pr\u00e9vention qui commence t\u00f4t, avant l\u2019arriv\u00e9e de la maladie ou des marques de vieillissement<\/strong>.<br \/>\nEn m\u00e9decine pro-aging les m\u00e9decins interpr\u00e8tent les tests de laboratoire de mani\u00e8re plus approfondie, permettant de trouver plus de d\u00e9ficiences hormonales et nutritionnelles, mod\u00e9r\u00e9es et s\u00e9v\u00e8res, ce qui les am\u00e8ne \u00e0 installer plus souvent et plus t\u00f4t chez un patient des traitements hormonaux et nutritionnels. Cette approche contraste avec celle de la plupart des autres m\u00e9decins qui prescrivent rarement des hormones et attendent que les d\u00e9ficiences soient devenues s\u00e9v\u00e8res avec d\u2019importants sympt\u00f4mes pour les traiter. Mais la simple pr\u00e9sence des taux bas en hormones et vitamines est scientifiquement associ\u00e9e \u00e0 un risque augment\u00e9 de maladie et parfois m\u00eame de mortalit\u00e9. Il vaut donc absolument la peine de traiter t\u00f4t les carences hormonales et nutritionnelles, m\u00eame celles dont les taux hormonaux et nutritionnels se trouvent encore dans les limites de valeurs de r\u00e9f\u00e9rence du laboratoire.<br \/>\nCette approche marginale de la m\u00e9decine pro-\u00e2ge respecte l\u2019adage \u00ab mieux vaut pr\u00e9venir que gu\u00e9rir \u00bb et implique de prendre un plus grand nombre de suppl\u00e9ments de vitamines et hormones \u00e9galement pour les d\u00e9ficiences mod\u00e9r\u00e9es. Cette approche remet en cause le dogme m\u00e9dical selon lequel il ne faudrait traiter que quand il y a maladie (bien d\u00e9clar\u00e9e), dogme assez tenace dans le milieu. Pourquoi devrait-on attendre d\u2019\u00eatre malade pour bien prendre soin de soi ?<\/li>\n<li><strong>Du bon dosage des th\u00e9rapies hormonales<\/strong><br \/>\nLes traitements hormonaux sont effectivement des traitements puissants.<br \/>\nEn administrer entra\u00eene souvent une grande diff\u00e9rence chez le patient gr\u00e2ce \u00e0 leur efficacit\u00e9 pour lutter contre le vieillissement. Ils peuvent permettre de rester jeune plus longtemps.<br \/>\nCependant, la dose des traitements hormonaux doit \u00eatre ajust\u00e9e \u00e0 chaque patient pour ne pas tomber dans des effets d\u00e9sagr\u00e9ables ou m\u00eame nuisibles dus au surdosage. Comme dans tout autre traitement m\u00e9dical, les doses trop fortes nuisent.<br \/>\nLa puissance des traitements hormonaux fait surgir des peurs injustifi\u00e9es, comme celle de voir un traitement hormonal favoriser \u00e0 la longue le d\u00e9veloppement d\u2019un cancer ou faire vieillir plus vite. Ces peurs sont infond\u00e9es quand les traitements sont bien choisis et bien ajust\u00e9s. En fait, de nombreuses \u00e9tudes soulignent l\u2019effet protecteur des traitements hormonaux et non pas l\u2019inverse.<br \/>\nLes taux \u00e9lev\u00e9s de certaines hormones peuvent prot\u00e9ger contre un cancer ou d\u2019autres maladies li\u00e9es \u00e0 l\u2019\u00e2ge et faire vivre plus longtemps avec une meilleure qualit\u00e9 de vie. Par exemple, un taux \u00e9lev\u00e9 en somatom\u00e9dine C ou IGF-1 prot\u00e8ge fortement contre le cancer du col de l\u2019ut\u00e9rus, un taux \u00e9lev\u00e9 de testost\u00e9rone appara\u00eet protecteur contre le cancer de l\u2019estomac, etc.<br \/>\nChez l\u2019animal aussi, des effets protecteurs contre le cancer et d\u2019autres maladies li\u00e9es \u00e0 l\u2019\u00e2ge ont \u00e9t\u00e9 d\u00e9montr\u00e9s avec parfois une augmentation de la long\u00e9vit\u00e9 (effets typiques du traitement \u00e0 la m\u00e9latonine, par exemple).<\/li>\n<\/ol>\n<p><\/div><div class=\"title_code\">Ne traite-t-on pas trop vite \u00e0 l\u2019aide d\u2019une th\u00e9rapie nutritionnelle ou hormonale multiple des patients qui ont des taux \u00ab normaux \u00bb ?<\/div>\n        <div class=\"content_code\"><br \/>\nArrive-t-il que l\u2019on traite des patients ayant des taux en micronutriments ou en hormones normaux, c\u2019est-\u00e0-dire compris dans les normes de r\u00e9f\u00e9rence du laboratoire ? Oui, cela arrive souvent, mais cela ne signifie pas pour autant que les hormonoth\u00e9rapeutes traiteraient trop vite ou trop facilement leurs patients avec des micronutriments ou des hormones. Cette fausse impression provient du fait que les nutritionnistes ou hormonoth\u00e9rapeutes traitent<strong> toutes les d\u00e9ficiences en micronutriments ou en hormones<\/strong> qui provoquent des plaintes et des signes physiques de carence, y compris celles dont les taux sanguins se situent dans l\u2019intervalle de r\u00e9f\u00e9rence du laboratoire (dans les taux les plus bas). Les nutritionnistes, hormonoth\u00e9rapeutes et m\u00e9decins pro-\u00e2ge visent \u00e0 amener leurs patients \u00e0 une sant\u00e9 optimale et non pas simplement \u00e0 \u00e9viter chez eux toute maladie grave li\u00e9e \u00e0 une carence hormonale tr\u00e8s s\u00e9v\u00e8re. La plupart des m\u00e9decins \u00abclassiques\u00bb, y compris les endocrinologues, choisissent de ne pas traiter les petites carences en micronutriments ou en hormones. Une <strong>mauvaise compr\u00e9hension de la signification des valeurs normales ou de r\u00e9f\u00e9rence du laboratoire<\/strong> est \u00e0 la base de ce malentendu fondamental. <strong>Les valeurs normales ou de r\u00e9f\u00e9rence des tests ne sont pas des valeurs de sant\u00e9 adapt\u00e9es au patient, mais des valeurs bas\u00e9es sur des statistiques !<\/strong> Elles informent uniquement sur les taux en micronutriments ou en hormone que pr\u00e9sentent 95 % des patients qui vont \u00e0 ce laboratoire pour faire une analyse nutritionnelle ou hormonale. 95 % des patients sont syst\u00e9matiquement situ\u00e9s dans ces valeurs normales (ou de r\u00e9f\u00e9rence), mais 2,5 % sont en dessous et 2,5 % au-dessus. Ce qui signifie que <strong>sur 100 % des patients chez qui l\u2019on soup\u00e7onne une anomalie micronutritionnelle ou hormonale, seuls 2,5 % auront un taux en dessous de la valeur de r\u00e9f\u00e9rence inf\u00e9rieure<\/strong>, alors qu\u2019il est possible que 30 % ou plus des patients souffrent aussi de d\u00e9ficience, peut-\u00eatre pas aussi s\u00e9v\u00e8rement que ceux qui sont en dessous de la limite du laboratoire, mais la carence est tout de m\u00eame pr\u00e9sente et donc mauvaise pour la sant\u00e9. Les intervalles de r\u00e9f\u00e9rence des tests micronutritionnels et hormonaux ont donc un \u00e9ventail trop large de normalit\u00e9 et ne correspondent pas \u00e0 des valeurs de sant\u00e9. Ces intervalles englobent des taux hormonaux \u00ab normaux \u00bb (bien que bas) de personnes qui peuvent \u00eatre r\u00e9ellement carenc\u00e9es en micronutriments ou en hormones et qui auraient besoin d\u2019un traitement. De plus, chaque laboratoire a ses propres valeurs de r\u00e9f\u00e9rence <strong>\u00e9tablies<\/strong> gr\u00e2ce aux patients qui ont fait le test au laboratoire et qui sont souvent des <strong>personnes d\u00e9j\u00e0 malades<\/strong>, avec un \u00e9tat de sant\u00e9 fragile (justifiant la demande du test). L\u2019autre facteur qui relativise la valeur inf\u00e9rieure et sup\u00e9rieure des r\u00e9f\u00e9rences normales des tests hormonaux est qu\u2019elles sont <strong>adapt\u00e9es vers le bas avec l\u2019\u00e2ge<\/strong>. Ceci <strong>parce que les taux<\/strong> d\u2019hormones diminuent avec l\u2019\u00e2ge et que les r\u00e9f\u00e9rences pour ces hormones sont souvent \u00e9tablies par cat\u00e9gorie d\u2019\u00e2ge. La limite inf\u00e9rieure est <strong>adapt\u00e9e vers le bas avec l\u2019\u00e2ge et<\/strong>, \u00e0 tort, consid\u00e9r\u00e9e par beaucoup de m\u00e9decins comme la limite entre bonne sant\u00e9 et d\u00e9ficience hormonale. Cette adaptation \u00e0 l\u2019\u00e2ge ne se justifie pas, parce que le corps d\u2019une personne \u00e2g\u00e9e conserve \u00e0 peu pr\u00e8s la m\u00eame taille et la m\u00eame quantit\u00e9 de tissus que lorsqu\u2019il \u00e9tait jeune adulte. Son corps n\u00e9cessite donc les m\u00eames taux hormonaux juv\u00e9niles pour rester en bonne sant\u00e9 et non pas les taux d\u00e9ficients du vieil \u00e2ge. Plus on avance en \u00e2ge, plus les carences hormonales apparaissent, mais moins celles-ci seront d\u00e9tect\u00e9es par les m\u00e9decins car ils sont beaucoup \u00e0 baser un diagnostic de d\u00e9ficience hormonale uniquement sur la pr\u00e9sence d\u2019un taux en dessous de la limite inf\u00e9rieure des r\u00e9f\u00e9rences du laboratoire. De nombreuses <strong>\u00e9tudes scientifiques<\/strong> ont d\u00e9montr\u00e9 que des personnes<strong> qui ont des taux d\u2019hormones situ\u00e9s dans les 25 %, 33 %, ou 50 % les plus bas des valeurs normales (ou de r\u00e9f\u00e9rence) pr\u00e9sentent des risques augment\u00e9s de d\u00e9velopper des maladies<\/strong> comme les maladies cardio-vasculaires, le diab\u00e8te, le surpoids, l\u2019ost\u00e9oporose, certains cancers, et m\u00eame parfois un risque augment\u00e9 de mort. Ces donn\u00e9es sont la preuve que les valeurs de r\u00e9f\u00e9rence de taux hormonaux ne sont pas des valeurs fiables de sant\u00e9, mais des valeurs qui permettent juste de savoir o\u00f9 l\u2019on se situe par rapport aux autres patients contr\u00f4l\u00e9s par le laboratoire.<\/p>\n<p><\/div><div class=\"title_code\">Dopage : l\u2019hormonoth\u00e9rapie correctrice des d\u00e9ficits hormonaux est-elle du dopage ? <\/div>\n        <div class=\"content_code\"><br \/>\nNon,<strong> l\u2019hormonoth\u00e9rapie de la m\u00e9decine pro-\u00e2ge ou m\u00e9decine reversing aging<\/strong> pallie les carences hormonales dues \u00e0 l\u2019\u00e2ge. Les doses d\u2019hormones donn\u00e9es sont des <strong>petites doses physiologiques<\/strong>, qui correspondent \u00e0 une fraction de la dose journali\u00e8re : un quart, un tiers, la moiti\u00e9 de la production journali\u00e8re par exemple. \u00c0 ces doses, si tout est bien \u00e9quilibr\u00e9 et adapt\u00e9 \u00e0 la d\u00e9ficience de la personne, il n\u2019y a <strong>pas d\u2019effets secondaires, uniquement des effets b\u00e9n\u00e9fiques<\/strong>. En cas de <strong>dopage<\/strong>, une personne \u2013 souvent non carenc\u00e9e \u2013 prend des <strong>doses \u00e9normes et excessives<\/strong> d\u2019hormones, de dix \u00e0 mille fois la production journali\u00e8re, ce qui d\u00e9s\u00e9quilibre fondamentalement le syst\u00e8me endocrinien (hormonal) et donne de nombreux signes et plaintes de surdosage.<\/p>\n<p><\/div><div class=\"title_code\">L\u2019hormonoth\u00e9rapie ne devrait-elle pas \u00eatre prescrite uniquement par des endocrinologues ?<\/div>\n        <div class=\"content_code\"><br \/>\nNon, car d\u2019une part la demande pour l\u2019hormonoth\u00e9rapie parmi le grand public est trop importante face au nombre des endocrinologues. Trop de patients veulent \u00eatre trait\u00e9s, un nombre dix \u00e0 cent fois plus important que les possibilit\u00e9s de consultation offertes par les endocrinologues. Les endocrinologues sont trop peu nombreux.<br \/>\nD\u2019autre part, les endocrinologues sont souvent trop peu exp\u00e9riment\u00e9s en ce qui concerne les hormonoth\u00e9rapies les plus r\u00e9centes comme la m\u00e9latonine, la DHEA, la pregn\u00e9nolone, l\u2019hormone de croissance, etc. Les endocrinologues officieux sont souvent tr\u00e8s bons pour traiter le diab\u00e8te et, parfois, mais pas souvent optimalement \u00e0 mon avis, exp\u00e9riment\u00e9s dans le traitement thyro\u00efdien.<br \/>\nDe plus, la consultation d\u2019endocrinologie classique de 15 \u00e0 20 minutes ne dure pas assez longtemps pour pouvoir appliquer de bons traitements hormonaux, surtout s\u2019il y en a plusieurs. Une bonne consultation pour des traitements hormonaux dure entre 45 minutes et 1 heure 15, et contient un examen physique approfondi que la plupart des endocrinologues officieux ne font pas. Ils se limitent souvent \u00e0 prendre la tension art\u00e9rielle, \u00e0 mesurer le poids et le pouls et \u00e0 palper la thyro\u00efde. Ce n\u2019est pas suffisant pour v\u00e9rifier les nombreux signes physiques possibles de dysfonction hormonale. Pour toutes ces raisons, les r\u00e9sultats d\u2019hormonoth\u00e9rapie sont souvent meilleurs chez les m\u00e9decins qui pratiquent la m\u00e9decine pr\u00e9ventive et anti-\u00e2ge ou pro-aging ou reversing aging, dont les possibilit\u00e9s diagnostiques et th\u00e9rapeutiques avec des traitements nutritionnels, di\u00e9t\u00e9tiques, psychologiques, et de toxicit\u00e9 environnementale d\u00e9passent le cadre de l\u2019endocrinologie traditionnelle.<\/p>\n<p><\/div><div class=\"title_code\">La m\u00e9decine pro-\u00e2ge et les hormonoth\u00e9rapies sont-elles des m\u00e9decines s\u00e9rieuses ?<\/div>\n        <div class=\"content_code\"><br \/>\nContrairement \u00e0 certaines formes d\u2019hom\u00e9opathie, de certaines m\u00e9decines alternatives et de certaines formes de m\u00e9decine traditionnelle, la m\u00e9decine anti-\u00e2ge et l\u2019hormonoth\u00e9rapie des carences hormonales li\u00e9es \u00e0 l\u2019\u00e2ge se basent sur une science m\u00e9dicale des plus solides soutenue par une vaste <strong>litt\u00e9rature scientifique<\/strong>. De plus, ce s\u00e9rieux est encore renforc\u00e9 par une <strong>approche m\u00e9dicale diagnostique et th\u00e9rapeutique en g\u00e9n\u00e9ral plus approfondie et longue<\/strong> que la majorit\u00e9 des autres types de consultations m\u00e9dicales.<\/p>\n<p><\/div><div class=\"title_code\">M\u00e9decine pro-\u00e2ge ou reversing aging : pas si co\u00fbteuse, pas commerciale.<\/div>\n        <div class=\"content_code\"><br \/>\nLes consultations de th\u00e9rapie hormonale et de m\u00e9decine pro-aging et reversing aging sont plus co\u00fbteuses parce que plus longues et plus approfondies. Ces m\u00e9decines exigent des consultations suivies sur une longue dur\u00e9e et une formation postuniversitaire pour se sp\u00e9cialiser dans cette discipline. Toutes ces choses ont en effet leur prix, et se retrouvent naturellement dans l\u2019honoraire de la consultation. Le co\u00fbt des consultations et des traitements tout compris reste cependant inf\u00e9rieur \u00e0 de nombreuses interventions chirurgicales, \u00e0 de nombreuses interventions de m\u00e9decine ou chirurgie esth\u00e9tique qui ne restaurent que l\u2019aspect ext\u00e9rieur d\u2019une personne, tandis que la m\u00e9decine pro-\u00e2ge et l\u2019hormonoth\u00e9rapie traitent tant la sant\u00e9 int\u00e9rieure que l\u2019aspect physique. Un entretien du corps bien n\u00e9cessaire, dont le co\u00fbt reste largement inf\u00e9rieur au co\u00fbt annuel d\u2019une voiture, de l\u2019essence et des r\u00e9parations qu\u2019elle engendre.<\/p>\n<p><\/div><div class=\"title_code\">Existe-t-il des formations en th\u00e9rapie hormonale et en m\u00e9decine anti-\u00e2ge ?<\/div>\n        <div class=\"content_code\"><br \/>\nIl existe plusieurs formations postuniversitaires reconnues de m\u00e9decine anti-\u00e2ge dans les universit\u00e9s : l\u2019universit\u00e9 de Floride aux USA en propose une, l\u2019universit\u00e9 de Dresde en Allemagne aussi, ainsi que l\u2019universit\u00e9 autonome de Barcelone en Espagne. La formation en morphom\u00e9decine et anti-\u00e2ge existe ou a exist\u00e9 aux universit\u00e9s de Montpellier et Ren\u00e9 Descartes \u00e0 Paris, en France. En Belgique, le CUNIC (Centre universitaire de Charleroi) a pr\u00e9sent\u00e9 la premi\u00e8re formation au monde en th\u00e9rapeutique anti-\u00e2ge en fran\u00e7ais en 2001, dont j\u2019ai \u00e9t\u00e9 l\u2019un des fondateurs et le superviseur principal, remplac\u00e9e plus tard par la formation en anglais l<strong>\u2019Anti-aging medicine specialization<\/strong> en 2004 et reconnue comme la formation officielle de la World Society Of Anti-Aging Medicine (plus de 7000 m\u00e9decins). Elle est organis\u00e9e par la Hertoghe Medical School (pour info : e-mail <a href=\"&#x6d;a&#x69;&#108;&#x74;&#111;:&#x77;&#111;&#x73;&#97;a&#x6d;&#64;&#x77;&#111;s&#x61;a&#x6d;&#46;&#x77;&#x73;\" target=\"_blank\">&#119;o&#x73;a&#x61;m&#x40;w&#x6f;s&#x61;a&#x6d;&#46;&#x77;&#115;<\/a> et site <a href=\"http:\/\/www.wosaam.ws\" target=\"_blank\">www.wosaam.ws<\/a> ou <a href=\"http:\/\/www.hertoghemedicalschool.eu\" target=\"_blank\">www.hertoghemedicalschool.eu<\/a>). Il existe aussi l<strong>\u2019Hormone Therapy Specialty<\/strong>, la formation officielle de l\u2019International Hormone Society (&gt; 3000 m\u00e9decins) ouverte aux m\u00e9decins de <strong>toute discipline m\u00e9dicale<\/strong> et organis\u00e9e \u00e9galement par la Hertoghe Medical School. Cette formation en hormonoth\u00e9rapie est beaucoup plus \u00e9tendue et vari\u00e9e que la formation gouvernementale et universitaire classique d\u2019endocrinologie qui comprend essentiellement une formation en diab\u00e8te et en troubles thyro\u00efdiens avec tr\u00e8s peu d\u2019information sur d\u2019autres traitements hormonaux. \u00c0 c\u00f4t\u00e9 de cette formation approfondie, il existe toute une s\u00e9rie de <strong>s\u00e9minaires de formation<\/strong> (T. Hertoghe, A4M, etc.),<strong> conf\u00e9rences et congr\u00e8s<\/strong> avec ateliers satellites pratiques. Pour info : e-mail <a href=\"&#109;&#x61;i&#x6c;&#x74;&#111;&#x3a;i&#x68;&#x73;&#64;&#x69;n&#x74;&#x6c;&#104;&#x6f;r&#x6d;&#x6f;&#110;&#x65;s&#x6f;&#x63;&#105;&#x65;t&#x79;&#x2e;&#111;&#x72;g\" target=\"_blank\">&#x69;&#x68;&#x73;&#64;&#105;&#110;tl&#x68;&#x6f;&#x72;&#x6d;&#111;&#110;es&#x6f;&#x63;&#x69;&#x65;&#116;&#121;&#46;o&#x72;&#x67;<\/a> et site <a href=\"http:\/\/www.intlhormonesociety.org\" target=\"_blank\">www.intlhormonesociety.org<\/a>, ou <a href=\"http:\/\/www.hertoghemedicalschool.eu\" target=\"_blank\">www.hertoghemedicalschool.eu<\/a>.<\/p>\n<p><\/div><div class=\"title_code\"> Comment trouver le m\u00e9decin qui peut vous aider ?<\/div>\n        <div class=\"content_code\"><br \/>\nConsultez un m\u00e9decin exp\u00e9riment\u00e9 en traitements hormonaux et nutritionnels. Ce m\u00e9decin doit non seulement \u00eatre capable de traiter les carences hormonales et nutritionnelles majeures (comme le font les m\u00e9decins travaillant dans les h\u00f4pitaux universitaires), mais aussi \u00eatre capable de traiter les d\u00e9ficits partiels et plus mod\u00e9r\u00e9s (comme le font les m\u00e9decins qui, dans des pratiques m\u00e9dicales priv\u00e9es, cherchent \u00e0 pr\u00e9venir le vieillissement).<br \/>\nAllez voir sur le site web de mon \u00e9cole pour m\u00e9decins <a href=\"http:\/\/www.hertoghemedicalschool.eu\" target=\"_blank\">www.hertoghemedicalschool.eu<\/a> les noms des 250 m\u00e9decins qui ont d\u00e9j\u00e0 r\u00e9ussi l\u2019examen d\u2019une des six formations de m\u00e9decine anti-\u00e2ge ou d\u2019hormonoth\u00e9rapie, ou sur le site <a href=\"http:\/\/www.worldhealth.net\" target=\"_blank\">www.worldhealth.net<\/a> de l\u2019American Academy of Anti-aging Medicine.<\/p>\n<p><\/div><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vous trouverez dans cette rubrique les r\u00e9ponses aux questions les plus fr\u00e9quemment pos\u00e9es par les patients lors de la consultation ainsi que les questions des personnes d\u00e9sireuses de venir \u00e0 la consultation.<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"cybocfi_hide_featured_image":"","footnotes":""},"class_list":["post-157","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.hertoghe.eu\/fr\/wp-json\/wp\/v2\/pages\/157","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hertoghe.eu\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.hertoghe.eu\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.hertoghe.eu\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hertoghe.eu\/fr\/wp-json\/wp\/v2\/comments?post=157"}],"version-history":[{"count":17,"href":"https:\/\/www.hertoghe.eu\/fr\/wp-json\/wp\/v2\/pages\/157\/revisions"}],"predecessor-version":[{"id":710,"href":"https:\/\/www.hertoghe.eu\/fr\/wp-json\/wp\/v2\/pages\/157\/revisions\/710"}],"wp:attachment":[{"href":"https:\/\/www.hertoghe.eu\/fr\/wp-json\/wp\/v2\/media?parent=157"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}